{"id":1715,"date":"2021-02-23T17:02:23","date_gmt":"2021-02-23T17:02:23","guid":{"rendered":"https:\/\/kristall-klar.ch\/?page_id=1715"},"modified":"2025-06-26T09:38:11","modified_gmt":"2025-06-26T07:38:11","slug":"buro-gewerbe","status":"publish","type":"page","link":"https:\/\/kristall-klar.ch\/en\/offices-commercial\/","title":{"rendered":"Offices &amp; Commercial"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1715\" class=\"elementor elementor-1715\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-07cbb1f elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"07cbb1f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5196493\" data-id=\"5196493\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-89a46fb elementor-widget elementor-widget-heading\" data-id=\"89a46fb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-large\">B\u00fcro &amp; Gewerbe<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-24e6d85 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"24e6d85\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-90f1e65 services-intro\" data-id=\"90f1e65\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b19ea60 elementor-widget elementor-widget-page_section\" data-id=\"b19ea60\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"page_section.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"tt-wrapper05 section-inner03\" style=\"background-image: url('')\">\n\t\t\t\t\t\t<div class=\"container container-fluid-xl\">\n\t\t\t\t\t\t\t<div class=\"row flex-sm-row-reverse\">\n\t\t\t\t\t\t\t\t<div class=\"col-sm-5 col-md-6\">\n\t\t\t\t\t\t\t\t\t<div class=\"extra-right-img\">\n\t\t\t\t\t\t\t\t\t\t<picture>\n\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"1708\" src=\"https:\/\/kristall-klar.ch\/wp-content\/uploads\/2025\/06\/kristall-klar-015-scaled.jpg\" class=\"attachment-full size-full wp-image-11058\" alt=\"\" srcset=\"https:\/\/kristall-klar.ch\/wp-content\/uploads\/2025\/06\/kristall-klar-015-scaled.jpg 2560w, https:\/\/kristall-klar.ch\/wp-content\/uploads\/2025\/06\/kristall-klar-015-300x200.jpg 300w, https:\/\/kristall-klar.ch\/wp-content\/uploads\/2025\/06\/kristall-klar-015-1024x683.jpg 1024w, https:\/\/kristall-klar.ch\/wp-content\/uploads\/2025\/06\/kristall-klar-015-768x512.jpg 768w, https:\/\/kristall-klar.ch\/wp-content\/uploads\/2025\/06\/kristall-klar-015-1536x1025.jpg 1536w, https:\/\/kristall-klar.ch\/wp-content\/uploads\/2025\/06\/kristall-klar-015-2048x1366.jpg 2048w, https:\/\/kristall-klar.ch\/wp-content\/uploads\/2025\/06\/kristall-klar-015-18x12.jpg 18w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t<\/picture>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"divider d-block d-sm-none\"><\/div>\n\t\t\t\t\t\t\t\t<div class=\"col-sm-7 col-md-6\">\n\t\t\t\t\t\t\t\t\t<div class=\"tt-text-indent-right\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"title-block\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"title-block__label\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<!-- Title -->\n\t\t\t\t\t\t\t\t\t\t\t<h2 class=\"title-block__title typo-title-text\"> Ein sauberes Umfeld ist ein produktives Umfeld <\/h2>\n\t\t\t\t\t\t\t\t\t\t\t<!-- Title -->\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<!-- content -->\n\t\t\t\t\t\t\t\t\t\t<p class=\"typo-content-text\">  <\/p>\n\t\t\t\t\t\t\t\t\t\t<!-- content -->\n\t\t\t\t\t\t\t\t\t\t<h4 class=\"tt-subtitle\">Unser 5-Sterne Service hilft mit, Ihrem Team ein Hochleistungsumfeld zu bieten.<\/h4>\n\t\t\t\t\t\t\t\t\t\t<!-- content two -->\n\t\t\t\t\t\t\t\t\t\t<p>In welcher Industrie Sie auch arbeiten, dass Arbeitsumfeld beeinflusst Leistung und Produktivit\u00e4t. Unsere erfahrenen Mitarbeiter\/innen sind in der Reinigung spezialisierter B\u00fcroger\u00e4te geschult und arbeiten diskret und respektvoll.<\/p>\n\n<p>Wir arbeiten mit Kunden aus verschiedenen Branchen mit unterschiedlichen Vertraulichkeits- und Fachanforderungen. Dazu geh\u00f6ren unter anderem B\u00fcros, Banken, Sicherheitsfirmen, Arztpraxen, Kliniken, Industriehallen, Fabriken, Schulen, Turnhallen und Sportanlagen.<\/p>\n\t\t\t\t\t\t\t\t\t\t<!-- content two -->\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7511cb3d elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7511cb3d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7b8e4327\" data-id=\"7b8e4327\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f769acc elementor-tabs-view-vertical services-nav-tab  elementor-hidden-phone elementor-widget elementor-widget-tabs\" data-id=\"6f769acc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-tabs\">\n\t\t\t<div class=\"elementor-tabs-wrapper\" role=\"tablist\" >\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1871\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1871\" aria-expanded=\"false\">Praxisreinigung<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1872\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1872\" aria-expanded=\"false\">Schulh\u00e4user<\/div>\n\t\t\t\t\t\t\t\t\t<div id=\"elementor-tab-title-1873\" class=\"elementor-tab-title elementor-tab-desktop-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1873\" aria-expanded=\"false\">Ausstellungsr\u00e4ume<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"elementor-tabs-content-wrapper\" role=\"tablist\" aria-orientation=\"vertical\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"true\" data-tab=\"1\" role=\"tab\" tabindex=\"0\" aria-controls=\"elementor-tab-content-1871\" aria-expanded=\"false\">Praxisreinigung<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1871\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1871\" tabindex=\"0\" hidden=\"false\"><p>\t\t<div data-elementor-type=\"page\" data-elementor-id=\"8597\" class=\"elementor elementor-8597\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-19ddcd9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"19ddcd9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4cf5bb6\" data-id=\"4cf5bb6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e4cf376 elementor-widget elementor-widget-heading\" data-id=\"e4cf376\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Praxisreinigung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d507eea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d507eea\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f3071a8 social-r--column-gap-right\" data-id=\"f3071a8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f692b5a elementor-widget elementor-widget-text-editor\" data-id=\"f692b5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Wir betreuen verschiedene \u00e4rztliche und therapeutische Praxen und haben in unserem Team die notwendigen Erfahrung die erh\u00f6hten hygienischen Anforderungen gerecht zu werden.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f23fafe elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"f23fafe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">T\u00e4gliche bis w\u00f6chentliche Unterhaltsreinigung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Desinfektionsreinigung Oberfl\u00e4chen, T\u00fcren Handgriffe etc<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Reinigung von Spezialbel\u00e4gen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-25e79e4 social-r--column-gap-left\" data-id=\"25e79e4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cfdc843 elementor-widget elementor-widget-image\" data-id=\"cfdc843\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"540\" src=\"https:\/\/kristall-klar.ch\/wp-content\/uploads\/2021\/08\/hospital-bed-cleaning-1.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-9366\" alt=\"Zwei Mitarbeiter reinigen ein Krankenhausbett mit einem Reinigungstuch\" srcset=\"https:\/\/kristall-klar.ch\/wp-content\/uploads\/2021\/08\/hospital-bed-cleaning-1.jpg 1024w, https:\/\/kristall-klar.ch\/wp-content\/uploads\/2021\/08\/hospital-bed-cleaning-1-300x158.jpg 300w, https:\/\/kristall-klar.ch\/wp-content\/uploads\/2021\/08\/hospital-bed-cleaning-1-768x405.jpg 768w, https:\/\/kristall-klar.ch\/wp-content\/uploads\/2021\/08\/hospital-bed-cleaning-1-18x9.jpg 18w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6f34b74 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6f34b74\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a131219\" data-id=\"a131219\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-267e9dd rq-btn elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"267e9dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjMzNjEiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">kostenlose beratung<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af6b465 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-phone elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"af6b465\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"far fa-dot-circle\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dffe7e4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dffe7e4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-42c2a7c\" data-id=\"42c2a7c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"2\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1872\" aria-expanded=\"false\">Schulh\u00e4user<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1872\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1872\" tabindex=\"0\" hidden=\"hidden\"><p>\t\t<div data-elementor-type=\"page\" data-elementor-id=\"8605\" class=\"elementor elementor-8605\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-19ddcd9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"19ddcd9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4cf5bb6\" data-id=\"4cf5bb6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e4cf376 elementor-widget elementor-widget-heading\" data-id=\"e4cf376\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Schulh\u00e4user<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d507eea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d507eea\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f3071a8 social-r--column-gap-right\" data-id=\"f3071a8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f692b5a elementor-widget elementor-widget-text-editor\" data-id=\"f692b5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Sehr hohe Effizienz und Gr\u00fcndlichkeit zeichnet unsere Arbeit in Schulh\u00e4usern aus. Nicht nur in Pandemiezeiten, sind Sauberkeit und Hygiene in Schulen besonders wichtig.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f23fafe elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"f23fafe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">T\u00e4gliche Unterhaltsreinigung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"> Grunndreinigungen w\u00e4hrend Schulferien<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">J\u00e4hrliche oder halbj\u00e4hrliche Fassaden- und Fensterreinigung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-25e79e4 social-r--column-gap-left\" data-id=\"25e79e4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cfdc843 elementor-widget elementor-widget-image\" data-id=\"cfdc843\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kristall-klar.ch\/wp-content\/uploads\/2021\/08\/Classroom-cleaning-1.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-9370\" alt=\"Mann in Uniform bei der Desinfektion eines Schultisches\" srcset=\"https:\/\/kristall-klar.ch\/wp-content\/uploads\/2021\/08\/Classroom-cleaning-1.jpg 1024w, https:\/\/kristall-klar.ch\/wp-content\/uploads\/2021\/08\/Classroom-cleaning-1-300x200.jpg 300w, https:\/\/kristall-klar.ch\/wp-content\/uploads\/2021\/08\/Classroom-cleaning-1-768x512.jpg 768w, https:\/\/kristall-klar.ch\/wp-content\/uploads\/2021\/08\/Classroom-cleaning-1-18x12.jpg 18w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6f34b74 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6f34b74\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a131219\" data-id=\"a131219\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af6b465 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-phone elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"af6b465\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"far fa-dot-circle\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dffe7e4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dffe7e4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-42c2a7c\" data-id=\"42c2a7c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-267e9dd rq-btn elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"267e9dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjMzNjEiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Kostenlose Beratung<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/p><\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-tab-title elementor-tab-mobile-title\" aria-selected=\"false\" data-tab=\"3\" role=\"tab\" tabindex=\"-1\" aria-controls=\"elementor-tab-content-1873\" aria-expanded=\"false\">Ausstellungsr\u00e4ume<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1873\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"tabpanel\" aria-labelledby=\"elementor-tab-title-1873\" tabindex=\"0\" hidden=\"hidden\"><p>\t\t<div data-elementor-type=\"page\" data-elementor-id=\"8611\" class=\"elementor elementor-8611\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-19ddcd9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"19ddcd9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4cf5bb6\" data-id=\"4cf5bb6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e4cf376 elementor-widget elementor-widget-heading\" data-id=\"e4cf376\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ausstellungsr\u00e4ume<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d507eea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d507eea\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f3071a8 social-r--column-gap-right\" data-id=\"f3071a8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f692b5a elementor-widget elementor-widget-text-editor\" data-id=\"f692b5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">F\u00fcr die Repr\u00e4sentation von Gegenst\u00e4nden in Austellungsr\u00e4umen ist die Sauberkeit besonders wichtig. Wir freuen uns die Austellungsr\u00e4ume diverser Kunden blitz-blank halten zu d\u00fcrfen.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f23fafe elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"f23fafe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Bodenreinigung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Glasvitrinen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Personal-Garderoben<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">B\u00fcror\u00e4umlichkeiten<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Sitzungszimmer<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Lounges<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Fassaden- &amp; Fensterreinigung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-25e79e4 social-r--column-gap-left\" data-id=\"25e79e4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cfdc843 elementor-widget elementor-widget-image\" data-id=\"cfdc843\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kristall-klar.ch\/wp-content\/uploads\/2021\/08\/Shop-window-cleaning-1.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-9368\" alt=\"Mann in Uniform mit Handschuhen putzt ein Schaufenster\" srcset=\"https:\/\/kristall-klar.ch\/wp-content\/uploads\/2021\/08\/Shop-window-cleaning-1.jpg 1024w, https:\/\/kristall-klar.ch\/wp-content\/uploads\/2021\/08\/Shop-window-cleaning-1-300x200.jpg 300w, https:\/\/kristall-klar.ch\/wp-content\/uploads\/2021\/08\/Shop-window-cleaning-1-768x512.jpg 768w, https:\/\/kristall-klar.ch\/wp-content\/uploads\/2021\/08\/Shop-window-cleaning-1-18x12.jpg 18w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6f34b74 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6f34b74\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a131219\" data-id=\"a131219\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-267e9dd rq-btn elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"267e9dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjMzNjEiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">kostenlose beratung<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af6b465 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-phone elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"af6b465\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"far fa-dot-circle\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dffe7e4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dffe7e4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-42c2a7c\" data-id=\"42c2a7c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/p><\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6dd17f72 elementor-widget__width-initial elementor-absolute elementor-widget-mobile__width-initial elementor-hidden-phone elementor-widget elementor-widget-heading\" data-id=\"6dd17f72\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">B\u00fcro &#038; Gewerbe<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4efc2194 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-heading\" data-id=\"4efc2194\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">B\u00fcro &#038; Gewerbe<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b20b6ef tab services-nav-tab  elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-accordion\" data-id=\"4b20b6ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1261\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1261\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Praxisreinigung<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1261\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1261\"><p>\t\t<div data-elementor-type=\"page\" data-elementor-id=\"8597\" class=\"elementor elementor-8597\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-19ddcd9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"19ddcd9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4cf5bb6\" data-id=\"4cf5bb6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e4cf376 elementor-widget elementor-widget-heading\" data-id=\"e4cf376\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Praxisreinigung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d507eea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d507eea\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f3071a8 social-r--column-gap-right\" data-id=\"f3071a8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f692b5a elementor-widget elementor-widget-text-editor\" data-id=\"f692b5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Wir betreuen verschiedene \u00e4rztliche und therapeutische Praxen und haben in unserem Team die notwendigen Erfahrung die erh\u00f6hten hygienischen Anforderungen gerecht zu werden.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f23fafe elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"f23fafe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">T\u00e4gliche bis w\u00f6chentliche Unterhaltsreinigung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Desinfektionsreinigung Oberfl\u00e4chen, T\u00fcren Handgriffe etc<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Reinigung von Spezialbel\u00e4gen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-25e79e4 social-r--column-gap-left\" data-id=\"25e79e4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cfdc843 elementor-widget elementor-widget-image\" data-id=\"cfdc843\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"540\" src=\"https:\/\/kristall-klar.ch\/wp-content\/uploads\/2021\/08\/hospital-bed-cleaning-1.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-9366\" alt=\"Zwei Mitarbeiter reinigen ein Krankenhausbett mit einem Reinigungstuch\" srcset=\"https:\/\/kristall-klar.ch\/wp-content\/uploads\/2021\/08\/hospital-bed-cleaning-1.jpg 1024w, https:\/\/kristall-klar.ch\/wp-content\/uploads\/2021\/08\/hospital-bed-cleaning-1-300x158.jpg 300w, https:\/\/kristall-klar.ch\/wp-content\/uploads\/2021\/08\/hospital-bed-cleaning-1-768x405.jpg 768w, https:\/\/kristall-klar.ch\/wp-content\/uploads\/2021\/08\/hospital-bed-cleaning-1-18x9.jpg 18w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6f34b74 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6f34b74\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a131219\" data-id=\"a131219\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-267e9dd rq-btn elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"267e9dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjMzNjEiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">kostenlose beratung<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af6b465 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-phone elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"af6b465\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"far fa-dot-circle\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dffe7e4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dffe7e4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-42c2a7c\" data-id=\"42c2a7c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1262\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1262\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Schulh\u00e4user<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1262\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1262\"><p>\t\t<div data-elementor-type=\"page\" data-elementor-id=\"8605\" class=\"elementor elementor-8605\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-19ddcd9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"19ddcd9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4cf5bb6\" data-id=\"4cf5bb6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e4cf376 elementor-widget elementor-widget-heading\" data-id=\"e4cf376\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Schulh\u00e4user<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d507eea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d507eea\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f3071a8 social-r--column-gap-right\" data-id=\"f3071a8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f692b5a elementor-widget elementor-widget-text-editor\" data-id=\"f692b5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Sehr hohe Effizienz und Gr\u00fcndlichkeit zeichnet unsere Arbeit in Schulh\u00e4usern aus. Nicht nur in Pandemiezeiten, sind Sauberkeit und Hygiene in Schulen besonders wichtig.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f23fafe elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"f23fafe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">T\u00e4gliche Unterhaltsreinigung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"> Grunndreinigungen w\u00e4hrend Schulferien<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">J\u00e4hrliche oder halbj\u00e4hrliche Fassaden- und Fensterreinigung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-25e79e4 social-r--column-gap-left\" data-id=\"25e79e4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cfdc843 elementor-widget elementor-widget-image\" data-id=\"cfdc843\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kristall-klar.ch\/wp-content\/uploads\/2021\/08\/Classroom-cleaning-1.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-9370\" alt=\"Mann in Uniform bei der Desinfektion eines Schultisches\" srcset=\"https:\/\/kristall-klar.ch\/wp-content\/uploads\/2021\/08\/Classroom-cleaning-1.jpg 1024w, https:\/\/kristall-klar.ch\/wp-content\/uploads\/2021\/08\/Classroom-cleaning-1-300x200.jpg 300w, https:\/\/kristall-klar.ch\/wp-content\/uploads\/2021\/08\/Classroom-cleaning-1-768x512.jpg 768w, https:\/\/kristall-klar.ch\/wp-content\/uploads\/2021\/08\/Classroom-cleaning-1-18x12.jpg 18w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6f34b74 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6f34b74\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a131219\" data-id=\"a131219\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-af6b465 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-phone elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"af6b465\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"far fa-dot-circle\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dffe7e4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dffe7e4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-42c2a7c\" data-id=\"42c2a7c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-267e9dd rq-btn elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"267e9dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjMzNjEiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Kostenlose Beratung<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1263\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1263\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-chevron-down\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-chevron-up\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Ausstellungsr\u00e4ume<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1263\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1263\"><p>\t\t<div data-elementor-type=\"page\" data-elementor-id=\"8611\" class=\"elementor elementor-8611\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-19ddcd9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"19ddcd9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4cf5bb6\" data-id=\"4cf5bb6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e4cf376 elementor-widget elementor-widget-heading\" data-id=\"e4cf376\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ausstellungsr\u00e4ume<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d507eea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d507eea\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f3071a8 social-r--column-gap-right\" data-id=\"f3071a8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f692b5a elementor-widget elementor-widget-text-editor\" data-id=\"f692b5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">F\u00fcr die Repr\u00e4sentation von Gegenst\u00e4nden in Austellungsr\u00e4umen ist die Sauberkeit besonders wichtig. Wir freuen uns die Austellungsr\u00e4ume diverser Kunden blitz-blank halten zu d\u00fcrfen.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f23fafe elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"f23fafe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Bodenreinigung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Glasvitrinen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Personal-Garderoben<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">B\u00fcror\u00e4umlichkeiten<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Sitzungszimmer<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Lounges<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Fassaden- &amp; Fensterreinigung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-25e79e4 social-r--column-gap-left\" data-id=\"25e79e4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cfdc843 elementor-widget elementor-widget-image\" data-id=\"cfdc843\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/kristall-klar.ch\/wp-content\/uploads\/2021\/08\/Shop-window-cleaning-1.jpg\" class=\"attachment-1536x1536 size-1536x1536 wp-image-9368\" alt=\"Mann in Uniform mit Handschuhen putzt ein Schaufenster\" srcset=\"https:\/\/kristall-klar.ch\/wp-content\/uploads\/2021\/08\/Shop-window-cleaning-1.jpg 1024w, https:\/\/kristall-klar.ch\/wp-content\/uploads\/2021\/08\/Shop-window-cleaning-1-300x200.jpg 300w, https:\/\/kristall-klar.ch\/wp-content\/uploads\/2021\/08\/Shop-window-cleaning-1-768x512.jpg 768w, https:\/\/kristall-klar.ch\/wp-content\/uploads\/2021\/08\/Shop-window-cleaning-1-18x12.jpg 18w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6f34b74 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6f34b74\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a131219\" data-id=\"a131219\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-267e9dd rq-btn elementor-mobile-align-justify elementor-widget elementor-widget-button\" data-id=\"267e9dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#elementor-action%3Aaction%3Dpopup%3Aopen%26settings%3DeyJpZCI6IjMzNjEiLCJ0b2dnbGUiOmZhbHNlfQ%3D%3D\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">kostenlose beratung<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af6b465 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-phone elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"af6b465\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"far fa-dot-circle\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dffe7e4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dffe7e4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-42c2a7c\" data-id=\"42c2a7c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2dccdc0a elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-phone elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"2dccdc0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"far fa-dot-circle\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e066157 elementor-widget elementor-widget-html\" data-id=\"7e066157\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script> \nif(window.outerWidth < 1025) {\njQuery(document).ready(function($) { \nvar delay = 100; setTimeout(function() { \n$('.elementor-tab-title').removeClass('elementor-active');\n $('.elementor-tab-content').css('display', 'none'); }, delay); \n}); }\n<\/script>\n\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3ccaa15 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"3ccaa15\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c844da1\" data-id=\"c844da1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f1b36cd elementor-widget elementor-widget-heading\" data-id=\"f1b36cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Unsere Dienstleistungen umfassen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5142ec74 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5142ec74\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-41b14eed\" data-id=\"41b14eed\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65357ecb elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"65357ecb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"\/hauswartungen\/\" class=\"elementor-icon elementor-animation-float\" tabindex=\"-1\" aria-label=\"Hauswartung\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"513\" height=\"513\" viewBox=\"0 0 513 513\" fill=\"none\"><g clip-path=\"url(#clip0)\"><path d=\"M113.65 398.352C109.74 394.452 103.411 394.452 99.5111 398.352C95.6011 402.262 95.6011 408.591 99.5111 412.491C103.411 416.401 109.74 416.401 113.65 412.491C117.55 408.591 117.55 402.262 113.65 398.352Z\" fill=\"#114A9F\"><\/path><path d=\"M137.29 151.425C137.29 151.425 137.289 151.424 137.288 151.424C137.307 151.443 137.335 151.471 137.29 151.425Z\" fill=\"#114A9F\"><\/path><path d=\"M383.28 284.292C371.15 272.148 352.204 272.916 340.844 284.288L333.776 291.356L312.564 270.144L368.05 214.658C407.194 227.355 450.401 217.15 479.767 187.786C510.695 156.869 520.368 110.566 504.408 69.8228C503.176 66.6828 500.444 64.3728 497.142 63.6828C493.838 62.9928 490.411 64.0148 488.026 66.3998L427.758 126.668C408.704 118.623 393.374 103.29 385.341 84.2438L445.602 23.9738C447.988 21.5888 449.009 18.1608 448.32 14.8588C447.63 11.5568 445.321 8.8248 442.18 7.5928C401.451 -8.3702 355.147 1.2998 324.216 32.2308C294.861 61.5868 284.655 104.802 297.345 143.957L241.858 199.436L167.748 125.327L158.423 76.0308C157.9 73.2648 156.235 70.8478 153.838 69.3728L43.5352 1.4978C39.5912 -0.928203 34.5002 -0.331203 31.2232 2.9428L2.94518 31.2218C-0.328819 34.4958 -0.926819 39.5888 1.50018 43.5328L69.3762 153.837C70.8512 156.234 73.2682 157.899 76.0332 158.422L125.329 167.748L199.434 241.861L14.6672 426.637C-4.87682 446.167 -4.89182 477.793 14.6622 497.335C34.1972 516.883 65.8222 516.891 85.3632 497.337L270.144 312.566L291.357 333.777L284.294 340.841C272.562 352.557 272.549 371.549 284.289 383.276L392.496 491.494C419.861 518.835 464.109 518.847 491.49 491.49C518.772 464.198 518.772 419.788 491.488 392.495L383.28 284.292ZM315.957 153.627C318.768 150.816 319.647 146.608 318.198 142.909C305.138 109.572 313.051 71.6788 338.357 46.3728C359.852 24.8758 390.419 15.9298 419.568 21.7258L366.642 74.6598C363.964 77.3378 363.029 81.2988 364.226 84.8898C374.064 114.414 397.571 137.925 427.104 147.781C430.699 148.98 434.661 148.046 437.34 145.366L490.272 92.4338C496.069 121.586 487.121 152.156 465.626 173.642C440.313 198.957 402.427 206.869 369.104 193.803C365.403 192.35 361.193 193.23 358.383 196.041L298.422 256.001L255.997 213.577L315.957 153.627ZM71.2192 483.198C59.5002 494.924 40.5372 494.934 28.8022 483.194C17.0762 471.475 17.0692 452.51 28.8052 440.78L213.574 256.002L256.001 298.424L71.2192 483.198ZM137.287 151.423C135.866 150.003 134.052 149.044 132.078 148.67L84.0932 139.592L22.6712 39.7788L39.7802 22.6698L139.593 84.0898L148.671 132.075C149.044 134.05 150.004 135.866 151.425 137.287L319.634 305.496L305.497 319.634C146.904 161.041 137.624 151.761 137.287 151.423ZM477.35 477.342C457.801 496.875 426.192 496.886 406.634 477.345L298.425 369.128C294.525 365.233 294.5 358.911 298.43 354.985C301.9 351.515 352.059 301.356 354.99 298.424C358.878 294.533 365.2 294.492 369.134 298.429L477.346 406.631C496.835 426.127 496.835 457.85 477.35 477.342Z\" fill=\"#114A9F\"><\/path><path d=\"M137.277 151.413C137.278 151.414 137.282 151.418 137.287 151.423L137.288 151.424C137.283 151.419 137.279 151.415 137.277 151.413Z\" fill=\"#114A9F\"><\/path><path d=\"M85.3629 426.639C81.4589 422.734 75.1299 422.734 71.2209 426.639L42.9429 454.917C39.0379 458.822 39.0379 465.153 42.9429 469.058C46.8479 472.963 53.1769 472.964 57.0849 469.058L85.3629 440.78C89.2669 436.876 89.2669 430.544 85.3629 426.639Z\" fill=\"#114A9F\"><\/path><path d=\"M456.131 413.71L376.205 333.775C372.302 329.871 365.97 329.869 362.064 333.775C358.158 337.68 358.158 344.01 362.063 347.916L441.989 427.851C445.893 431.756 452.225 431.757 456.13 427.851C460.036 423.947 460.036 417.616 456.131 413.71Z\" fill=\"#114A9F\"><\/path><path d=\"M427.852 441.987L347.917 362.062C344.012 358.158 337.68 358.158 333.776 362.063C329.871 365.969 329.871 372.299 333.777 376.205L413.712 456.13C417.617 460.035 423.948 460.034 427.853 456.129C431.757 452.224 431.757 445.893 427.852 441.987Z\" fill=\"#114A9F\"><\/path><\/g><defs><clipPath id=\"clip0\"><rect width=\"512.003\" height=\"512.003\" fill=\"white\"><\/rect><\/clipPath><\/defs><\/svg>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"\/hauswartungen\/\" >\n\t\t\t\t\t\t\tHauswartung\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-666650b1 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"666650b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"\/fenster-fassaden\/\" class=\"elementor-icon elementor-animation-float\" tabindex=\"-1\" aria-label=\"Lamellen- &amp; Storenreinigung\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"512\" height=\"512\" viewBox=\"0 0 512 512\" fill=\"none\"><path d=\"M504 8H72V153.184C35.728 159.352 8 190.928 8 228.928V239.736C8 262.624 18.088 284.168 35.672 298.824L56 315.76V329.144C50.528 330.552 45.472 333.288 41.376 337.384C35.336 343.424 32 351.464 32 360.008V504.008H160V471.664C166.752 470.96 173.4 469.072 179.504 466.032L199.592 456L193.104 472.784C189.12 485.4 196.136 498.912 208.752 502.896C211.104 503.64 213.544 504.024 216 504.024C226.512 504.024 235.704 497.288 238.792 487.512L255.616 440H504V8ZM45.92 286.528C31.992 274.92 24 257.864 24 239.736V228.928C24 195.336 51.328 168.016 84.912 168.016C95.944 168.016 106.784 171.016 116.248 176.696L135.64 188.336C133.64 199.48 123.448 208.016 111.328 208.016H90.232L82.216 232.056C67.624 232.864 56 245 56 259.792C56 269.6 61.048 278.488 69.312 283.504L61.36 299.4L45.92 286.528ZM374.304 193.296C378.232 194.976 381.272 198.088 382.856 202.056C383.64 204.024 384.016 206.08 384 208.136V208.24C383.968 210.304 383.536 212.36 382.696 214.312C379.328 222.192 369.664 226.128 361.68 222.696L249.688 174.696C245.76 173.016 242.72 169.904 241.136 165.936C239.552 161.968 239.608 157.616 241.296 153.68C243.816 147.8 249.584 144 255.992 144C258.168 144 260.296 144.44 262.312 145.304L374.304 193.296ZM328 225.672L355.368 237.4C359.384 239.128 363.64 240 368 240C373.768 240 379.232 238.392 384 235.632V264C384 268.408 380.408 272 376 272H368C354.768 272 344 282.768 344 296V368C344 372.408 340.408 376 336 376C331.592 376 328 372.408 328 368V225.672ZM309.704 217.832L260.048 375.072C255.832 371.672 250.792 369.416 245.344 368.504L294.92 211.504L309.704 217.832ZM227.912 370.584C227.192 370.88 226.416 371.024 225.728 371.376L160 403.832V392.064C160 388.816 159.688 385.64 159.152 382.528L236.312 343.96L227.912 370.584ZM144 394.76L99.912 350.672L111.152 352.712C130.184 356.168 144 372.72 144 392.064V394.76ZM88 304.008V320.008H104V335.144L73.928 329.68L73.92 329.728C73.288 329.52 72.648 329.312 72 329.144V313.896L90.728 276.432L78.504 270.32C74.496 268.32 72 264.28 72 259.792C72 253.296 77.288 248.016 83.776 248.016H93.768L101.768 224.016H111.336C118.36 224.016 124.888 222.096 130.68 218.992C142.28 229.8 157.52 247.448 159.736 267.208L144 275.064V291.064C144 296 141.256 300.432 136.84 302.64C135.048 303.536 133.048 304.008 131.048 304.008H88ZM52.688 348.696C55.712 345.672 59.728 344.008 64 344.008C68.272 344.008 72.288 345.672 75.312 348.696L113.648 387.032L91.024 409.656L52.688 371.312C49.664 368.304 48 364.288 48 360.008C48 355.728 49.664 351.72 52.688 348.696V348.696ZM48 488.008V389.264L114.168 455.432C122.272 463.544 132.792 468.96 144 471.04V488.016H48V488.008ZM172.36 451.72C157.096 459.32 137.456 456.096 125.48 444.112L102.336 420.968L124.96 398.344L152.16 425.544L232.832 385.696C240.56 381.848 250.488 385.184 254.312 392.864C256.224 396.68 256.528 401.016 255.176 405.064C253.824 409.12 250.976 412.408 247.152 414.32L172.36 451.72ZM223.624 482.416C222.32 486.536 217.792 488.976 213.576 487.632C209.376 486.304 207.04 481.8 208.2 478.072L220.856 445.368L240.176 435.712L223.624 482.416ZM488 424H261.288L261.432 423.608C265.456 419.96 268.6 415.432 270.36 410.136C272.224 404.536 272.4 398.688 271.144 393.088L312 263.704V368C312 381.232 322.768 392 336 392C349.232 392 360 381.232 360 368V296C360 291.592 363.592 288 368 288H376C389.232 288 400 277.232 400 264V208.512C400 208.416 400 208.328 400 208.232V208H399.976C399.976 203.984 399.248 199.96 397.704 196.12C394.536 188.184 388.456 181.952 380.6 178.592L315.36 150.632L270.648 83.56L257.336 92.432L288.44 139.088L268.608 130.584C264.592 128.872 260.344 128 255.992 128C243.16 128 231.616 135.616 226.592 147.392C223.224 155.256 223.112 163.952 226.288 171.888C229.456 179.824 235.536 186.056 243.392 189.416L280.144 205.168L242.968 322.896C242.552 323.08 242.096 323.192 241.688 323.392L153.984 367.232C147.208 353.6 135.096 343.128 120 338.616V320.016H131.056C135.528 320.016 140 318.96 144 316.96C153.872 312.024 160 302.112 160 291.072V284.96L176 276.96V272.016C176 245.448 157.552 222.576 143.12 208.736C148.488 202.104 151.88 193.888 152 184.864V179.488L124.488 162.984C113.424 156.344 100.856 152.752 88 152.232V24H488V424Z\" fill=\"#114A9F\"><\/path><path d=\"M128 256C132.418 256 136 252.418 136 248C136 243.582 132.418 240 128 240C123.582 240 120 243.582 120 248C120 252.418 123.582 256 128 256Z\" fill=\"#114A9F\"><\/path><path d=\"M456 256H472V272H456V256Z\" fill=\"#114A9F\"><\/path><path d=\"M456 384H472V400H456V384Z\" fill=\"#114A9F\"><\/path><path d=\"M456 320H472V336H456V320Z\" fill=\"#114A9F\"><\/path><path d=\"M456 288H472V304H456V288Z\" fill=\"#114A9F\"><\/path><path d=\"M456 352H472V368H456V352Z\" fill=\"#114A9F\"><\/path><path d=\"M136 40H152V56H136V40Z\" fill=\"#114A9F\"><\/path><path d=\"M104 40H120V56H104V40Z\" fill=\"#114A9F\"><\/path><path d=\"M168 40H184V56H168V40Z\" fill=\"#114A9F\"><\/path><path d=\"M369.333 44.3062L382.645 35.4262L478.695 179.415L465.383 188.295L369.333 44.3062Z\" fill=\"#114A9F\"><\/path><path d=\"M145.365 140.37L158.677 131.49L254.727 275.479L241.415 284.359L145.365 140.37Z\" fill=\"#114A9F\"><\/path><\/svg>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"\/fenster-fassaden\/\" >\n\t\t\t\t\t\t\tLamellen- &amp; Storenreinigung\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1770738f elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"1770738f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"\/spezialreinigung\/#disinfection_treatment\" class=\"elementor-icon elementor-animation-float\" tabindex=\"-1\" aria-label=\"Desinfektionsreinigung\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"512\" height=\"512\" viewBox=\"0 0 512 512\" fill=\"none\"><path d=\"M350 20C355.523 20 360 15.5228 360 10C360 4.47715 355.523 0 350 0C344.477 0 340 4.47715 340 10C340 15.5228 344.477 20 350 20Z\" fill=\"#114A9F\"><\/path><path d=\"M350 60C355.523 60 360 55.5228 360 50C360 44.4772 355.523 40 350 40C344.477 40 340 44.4772 340 50C340 55.5228 344.477 60 350 60Z\" fill=\"#114A9F\"><\/path><path d=\"M350 100C355.523 100 360 95.5228 360 90C360 84.4772 355.523 80 350 80C344.477 80 340 84.4772 340 90C340 95.5228 344.477 100 350 100Z\" fill=\"#114A9F\"><\/path><path d=\"M310 40C315.523 40 320 35.5228 320 30C320 24.4772 315.523 20 310 20C304.477 20 300 24.4772 300 30C300 35.5228 304.477 40 310 40Z\" fill=\"#114A9F\"><\/path><path d=\"M310 80C315.523 80 320 75.5228 320 70C320 64.4772 315.523 60 310 60C304.477 60 300 64.4772 300 70C300 75.5228 304.477 80 310 80Z\" fill=\"#114A9F\"><\/path><path d=\"M160 416V386H190C195.522 386 200 381.523 200 376V336C200 330.477 195.522 326 190 326H160V296C160 290.477 155.522 286 150 286H110C104.478 286 100 290.477 100 296V326H70C64.478 326 60 330.477 60 336V376C60 381.523 64.478 386 70 386H100V416C100 421.523 104.478 426 110 426H150C155.522 426 160 421.523 160 416ZM140 376V406H120V376C120 370.477 115.522 366 110 366H80V346H110C115.522 346 120 341.523 120 336V306H140V336C140 341.523 144.478 346 150 346H180V366H150C144.478 366 140 370.477 140 376Z\" fill=\"#114A9F\"><\/path><path d=\"M502 0C496.478 0 492 4.477 492 10V86H482C465.458 86 452 99.458 452 116V166H406V156C406 139.458 392.542 126 376 126C359.458 126 346 139.458 346 156V356C346 372.542 359.458 386 376 386C392.542 386 406 372.542 406 356V226H452V276C452 292.542 465.458 306 482 306H492V502C492 507.523 496.478 512 502 512C507.522 512 512 507.523 512 502V10C512 4.477 507.522 0 502 0ZM386 356C386 361.514 381.514 366 376 366C370.486 366 366 361.514 366 356V156C366 150.486 370.486 146 376 146C381.514 146 386 150.486 386 156V356ZM406 206V186H452V206H406ZM482 286C476.486 286 472 281.514 472 276V116C472 110.486 476.486 106 482 106H492V286H482Z\" fill=\"#114A9F\"><\/path><path d=\"M130 512C135.523 512 140 507.523 140 502C140 496.477 135.523 492 130 492C124.477 492 120 496.477 120 502C120 507.523 124.477 512 130 512Z\" fill=\"#114A9F\"><\/path><path d=\"M30 512H85C90.522 512 95 507.523 95 502C95 496.477 90.522 492 85 492H30C24.486 492 20 487.514 20 482V316C20 255.798 48.733 194.976 93.426 160H170C186.542 160 200 173.458 200 190V236C200 240.197 202.238 242.397 204.17 244.297C213.032 253.008 240 279.515 240 325.71V482C240 487.514 235.514 492 230 492H175C169.478 492 165 496.477 165 502C165 507.523 169.478 512 175 512H230C246.542 512 260 498.542 260 482V325.71C260 291.518 247.353 259.078 220 231.822V190C220 165.854 202.795 145.652 180 141.006V109.057C196.677 129.05 220.04 140 247.66 140C253.182 140 257.66 135.523 257.66 130C257.66 124.477 253.182 120 247.66 120C210.942 120 192.59 96.701 183.694 77.459C194.975 75.203 263.058 61.586 271.96 59.805C276.636 58.871 280 54.767 280 50V10C280 4.477 275.522 0 270 0H50C22.43 0 0 22.43 0 50V70C0 75.523 4.478 80 10 80H50C66.542 80 80 93.458 80 110V145.105C56.105 164.083 36.138 189.617 22.079 219.274C7.635 249.743 0 283.19 0 316V482C0 498.542 13.458 512 30 512ZM100 120H160V140H100V120ZM260 41.802L240 45.802V20H260V41.802ZM50 60H20V50C20 33.458 33.458 20 50 20H220V49.802L168.039 60.194C163.386 61.111 160.338 64.411 160 70.167V70.211V100H98.994C94.348 77.205 74.146 60 50 60V60Z\" fill=\"#114A9F\"><\/path><\/svg>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"\/spezialreinigung\/#disinfection_treatment\" >\n\t\t\t\t\t\t\tDesinfektionsreinigung\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2bc4f471\" data-id=\"2bc4f471\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-760996b3 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"760996b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"\/umzugsreinigung\/\" class=\"elementor-icon elementor-animation-float\" tabindex=\"-1\" aria-label=\"Umzugsreinigung\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"512\" height=\"512\" viewBox=\"0 0 512 512\" fill=\"none\"><path d=\"M492.264 228.066H350.581V211.115C350.581 196.182 338.432 184.033 323.499 184.033C308.566 184.033 296.417 196.182 296.417 211.115V228.066H154.735C144.532 228.066 136.113 235.848 135.101 245.788C135.034 246.451 134.999 247.123 134.999 247.803V376.726C134.999 387.609 143.853 396.463 154.735 396.463H178.63V450.214H75.644V189.6L247.945 74.9852L420.245 189.601V210.416C420.245 214.462 423.525 217.741 427.57 217.741C431.615 217.741 434.895 214.462 434.895 210.416V199.346L457.096 214.114C465.496 219.702 476.35 219.702 484.751 214.114C491.725 209.475 495.889 201.704 495.889 193.327C495.889 184.951 491.725 177.18 484.751 172.542L255.039 19.7342C250.729 16.8672 245.161 16.8672 240.852 19.7342L107.567 108.397C104.199 110.637 103.284 115.184 105.525 118.553C107.766 121.921 112.314 122.836 115.681 120.594L247.945 32.6102L476.638 184.739C479.562 186.685 481.24 189.815 481.24 193.328C481.24 196.841 479.562 199.971 476.638 201.917C473.167 204.226 468.682 204.226 465.211 201.917L255.039 62.1082C250.729 59.2422 245.161 59.2402 240.852 62.1082L30.678 201.917C27.208 204.224 22.723 204.226 19.252 201.916C16.327 199.971 14.65 196.841 14.65 193.328C14.65 189.815 16.327 186.685 19.252 184.739L77.787 145.801C81.155 143.561 82.07 139.014 79.829 135.645C77.588 132.278 73.041 131.362 69.673 133.604L11.138 172.541C4.164 177.18 0 184.95 0 193.328C0 201.706 4.164 209.476 11.138 214.114C15.339 216.909 20.151 218.306 24.966 218.306C29.779 218.305 34.594 216.908 38.793 214.114L60.994 199.346V450.214H32.921C20.734 450.214 10.82 460.129 10.82 472.315C10.82 484.502 20.734 494.416 32.921 494.416H462.969C475.156 494.416 485.07 484.501 485.07 472.315C485.07 460.128 475.156 450.214 462.969 450.214H434.896V414.111C434.896 410.065 431.616 406.786 427.571 406.786C423.526 406.786 420.246 410.065 420.246 414.111V450.214H350.582V396.463H492.264C503.147 396.463 512 387.609 512 376.726V247.803C512 236.92 503.146 228.066 492.264 228.066ZM311.067 211.115C311.067 204.26 316.644 198.683 323.499 198.683C330.354 198.683 335.931 204.26 335.931 211.115V228.066H311.067V211.115V211.115ZM296.417 479.766H32.921C28.813 479.766 25.47 476.424 25.47 472.315C25.47 468.206 28.812 464.864 32.921 464.864H296.417V479.766ZM296.417 450.214H193.28V396.463H296.417V450.214V450.214ZM335.931 479.766H311.067V396.462H335.931V479.766ZM462.969 464.864C467.077 464.864 470.42 468.206 470.42 472.315C470.42 476.424 467.078 479.766 462.969 479.766H350.581V464.864H462.969V464.864ZM492.264 381.813H154.735C151.93 381.813 149.649 379.532 149.649 376.726V247.803C149.649 244.999 151.93 242.717 154.735 242.717L492.264 242.716C495.069 242.716 497.35 244.997 497.35 247.803V376.726C497.35 379.531 495.069 381.813 492.264 381.813Z\" fill=\"#114A9F\"><\/path><path d=\"M247.945 107.233C222.5 107.233 201.799 127.934 201.799 153.379C201.799 178.824 222.5 199.526 247.945 199.526C273.39 199.526 294.091 178.825 294.091 153.379C294.091 127.935 273.39 107.233 247.945 107.233ZM240.62 184.006C229.118 181.255 220.052 172.18 217.311 160.673H240.62V184.006ZM240.62 146.023H217.326C220.084 134.545 229.139 125.499 240.62 122.753V146.023ZM255.27 122.753C266.752 125.499 275.807 134.546 278.564 146.023H255.27V122.753ZM255.27 184.006V160.673H278.578C275.838 172.18 266.772 181.254 255.27 184.006Z\" fill=\"#114A9F\"><\/path><path d=\"M255.896 342.637L241.99 316.845C249.95 314.404 255.894 307.823 255.894 295.616C255.894 278.74 244.643 273.434 230.739 273.434H209.724C207.071 273.434 205.266 275.451 205.266 277.679V346.67C205.266 349.536 208.768 351.022 212.165 351.022C215.667 351.022 219.064 349.536 219.064 346.67V318.967H227.98L243.052 348.262C244.114 350.385 245.918 351.553 247.829 351.553C251.862 351.553 256.426 347.838 256.426 344.336C256.426 343.912 256.32 343.168 255.896 342.637ZM230.739 308.142H219.064V285.534H230.739C237.639 285.534 242.096 288.506 242.096 296.891C242.096 305.277 237.638 308.142 230.739 308.142Z\" fill=\"#114A9F\"><\/path><path d=\"M311.718 338.922H281.68V317.587H297.813C300.785 317.587 302.165 314.722 302.165 312.28C302.165 309.415 300.572 306.76 297.813 306.76H281.68V285.532H311.718V285.534C314.477 285.534 316.07 282.668 316.07 279.377C316.07 276.512 314.69 273.434 311.718 273.434H273.932C270.854 273.434 267.882 274.92 267.882 277.786V346.67C267.882 349.536 270.854 351.022 273.932 351.022H311.718C314.69 351.022 316.07 347.943 316.07 345.078C316.07 341.787 314.477 338.922 311.718 338.922Z\" fill=\"#114A9F\"><\/path><path d=\"M370.834 273.434C367.332 273.434 363.935 274.707 363.935 277.679V320.347L343.449 280.758C340.159 274.495 338.142 273.434 333.154 273.434C329.652 273.434 326.255 274.814 326.255 277.786V346.67C326.255 349.536 329.651 351.022 333.154 351.022C336.55 351.022 340.053 349.536 340.053 346.67V304.002L362.874 346.67C364.679 349.96 367.544 351.022 370.834 351.022C374.23 351.022 377.733 349.536 377.733 346.67V277.68C377.733 274.708 374.231 273.434 370.834 273.434Z\" fill=\"#114A9F\"><\/path><path d=\"M436.742 273.434H391.845C388.873 273.434 387.493 276.619 387.493 279.59C387.493 282.986 389.086 285.853 391.845 285.853H407.447V346.671C407.447 349.537 410.843 351.023 414.347 351.023C417.743 351.023 421.246 349.537 421.246 346.671V285.853H436.742C439.501 285.853 441.093 282.881 441.093 279.59C441.093 276.619 439.714 273.434 436.742 273.434Z\" fill=\"#114A9F\"><\/path><\/svg>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"\/umzugsreinigung\/\" >\n\t\t\t\t\t\t\tUmzugsreinigung\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-239ec3b4 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"239ec3b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"\/spezialreinigung#specialised_services\" class=\"elementor-icon elementor-animation-float\" tabindex=\"-1\" aria-label=\"Teppich &amp; B\u00f6den\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"512\" height=\"512\" viewBox=\"0 0 512 512\" fill=\"none\"><path d=\"M94.395 208.437H106.868C111.016 208.437 114.383 205.074 114.383 200.921C114.383 196.773 111.016 193.41 106.868 193.41H94.395C90.2427 193.41 86.8794 196.773 86.8794 200.921C86.8794 205.074 90.2427 208.437 94.395 208.437Z\" fill=\"#114A9F\"><\/path><path d=\"M106.868 317.257H94.395C90.2427 317.257 86.8794 320.621 86.8794 324.769C86.8794 328.921 90.2427 332.285 94.395 332.285H106.868C111.016 332.285 114.383 328.921 114.383 324.769C114.383 320.621 111.016 317.257 106.868 317.257Z\" fill=\"#114A9F\"><\/path><path d=\"M107.743 428.858C81.2036 428.858 61.1919 439.972 61.1919 454.714C61.1919 469.456 81.2036 480.573 107.743 480.573C134.282 480.573 154.293 469.456 154.293 454.714C154.293 439.972 134.282 428.858 107.743 428.858ZM107.743 465.542C87.2661 465.542 76.2192 457.854 76.2192 454.714C76.2192 451.569 87.2661 443.886 107.743 443.886C128.219 443.886 139.266 451.569 139.266 454.714C139.266 457.854 128.219 465.542 107.743 465.542Z\" fill=\"#114A9F\"><\/path><path d=\"M134.887 71.1758L142.743 75.4727C149.329 79.0742 154.711 84.457 158.313 91.043L162.606 98.8945C165.961 105.027 172.383 108.832 179.368 108.832C186.356 108.832 192.774 105.023 196.129 98.8945L200.422 91.043C204.024 84.457 209.411 79.0742 215.997 75.4727L223.848 71.1758C229.977 67.8242 233.786 61.4023 233.786 54.418C233.786 47.4297 229.977 41.0078 223.848 37.6562L215.997 33.3633C209.411 29.7617 204.024 24.375 200.422 17.7891L196.129 9.9375C192.774 3.80859 186.356 0 179.368 0C172.383 0 165.961 3.80859 162.606 9.9375L158.313 17.7891C154.711 24.375 149.329 29.7617 142.743 33.3633L134.887 37.6562C128.758 41.0078 124.954 47.4297 124.954 54.418C124.954 61.4023 128.758 67.8242 134.887 71.1758ZM142.098 50.8438L149.954 46.5469C159.063 41.5625 166.512 34.1133 171.497 25L175.793 17.1484C176.84 15.2344 178.641 15.0273 179.368 15.0273C180.094 15.0273 181.895 15.2344 182.942 17.1484L187.235 25C192.219 34.1133 199.672 41.5625 208.782 46.5469L216.633 50.8438C218.547 51.8867 218.754 53.6914 218.754 54.418C218.754 55.1445 218.547 56.9453 216.633 57.9922L208.782 62.2852C199.668 67.2695 192.219 74.7188 187.235 83.832L182.942 91.6836C181.895 93.5977 180.094 93.8047 179.368 93.8047C178.641 93.8047 176.836 93.5977 175.793 91.6836L171.497 83.832C166.512 74.7188 159.063 67.2695 149.95 62.2852L142.098 57.9922C140.184 56.9453 139.977 55.1406 139.977 54.418C139.981 53.6914 140.184 51.8906 142.098 50.8438Z\" fill=\"#114A9F\"><\/path><path d=\"M109.418 285.425C124.141 285.425 136.122 275.296 136.122 262.847C136.122 250.398 124.141 240.269 109.418 240.269C94.6919 240.269 82.7114 250.398 82.7114 262.847C82.7114 275.292 94.6919 285.425 109.418 285.425ZM109.418 255.296C116.297 255.296 121.094 259.273 121.094 262.843C121.094 266.417 116.297 270.394 109.418 270.394C102.536 270.394 97.7388 266.417 97.7388 262.843C97.7388 259.273 102.536 255.296 109.418 255.296V255.296Z\" fill=\"#114A9F\"><\/path><path d=\"M468.958 300.723C482.086 300.723 492.762 290.043 492.762 276.914C492.762 263.789 482.086 253.109 468.958 253.109H457.043C452.891 253.109 449.528 256.473 449.528 260.625C449.528 264.773 452.891 268.137 457.043 268.137H468.958C473.797 268.137 477.735 272.074 477.735 276.914C477.735 281.758 473.797 285.695 468.958 285.695H431.668V237.168H468.958C482.086 237.168 492.762 226.488 492.762 213.359C492.762 200.234 482.086 189.555 468.958 189.555H427.524C425.262 185.133 422.149 181.18 418.352 177.945L422.965 175.422C430.211 171.461 434.536 164.164 434.536 155.91C434.536 147.648 430.211 140.355 422.965 136.391L412.985 130.934C404.27 126.168 397.145 119.043 392.383 110.332L386.922 100.348C382.961 93.1055 375.665 88.7773 367.407 88.7773C359.149 88.7773 351.852 93.1016 347.891 100.348L342.43 110.332C337.668 119.043 330.543 126.168 321.829 130.934L311.848 136.391C304.602 140.355 300.278 147.648 300.278 155.91C300.278 160.742 301.77 165.242 304.454 168.945H195.426C194.813 153.563 185.301 139.406 168.434 128.941C152.11 118.812 130.555 113.234 107.743 113.234C84.9341 113.234 63.3794 118.812 47.0513 128.941C29.6099 139.766 20.0005 154.531 20.0005 170.52V454.715C20.0005 470.707 29.6099 485.473 47.0513 496.293C63.3794 506.422 84.9341 512 107.743 512H393.887C408.54 512 421.258 503.609 427.524 491.391H468.958C482.083 491.391 492.762 480.711 492.762 467.582C492.762 454.457 482.083 443.777 468.958 443.777H431.668V427.832H468.958C482.083 427.832 492.762 417.152 492.762 404.027C492.762 390.898 482.083 380.219 468.958 380.219H431.668V364.277H468.958C482.083 364.277 492.762 353.598 492.762 340.473C492.762 327.344 482.083 316.664 468.958 316.664H431.668V300.723H468.958ZM468.958 204.582C473.797 204.582 477.735 208.52 477.735 213.359C477.735 218.203 473.797 222.141 468.958 222.141H431.668C431.668 222.141 431.641 205.293 431.602 204.582H468.958ZM319.059 149.574L329.04 144.117C340.278 137.973 349.469 128.781 355.618 117.539L361.075 107.559C362.93 104.172 366.122 103.805 367.407 103.805C368.692 103.805 371.883 104.172 373.739 107.559L379.196 117.539C385.344 128.781 394.536 137.973 405.774 144.117L415.754 149.574C419.141 151.43 419.508 154.621 419.508 155.906C419.508 157.191 419.145 160.387 415.754 162.238L405.774 167.695C394.536 173.844 385.344 183.035 379.2 194.273L373.739 204.254C371.887 207.641 368.696 208.008 367.407 208.008C366.122 208.008 362.93 207.641 361.079 204.254L355.618 194.273C349.469 183.031 340.282 173.844 329.04 167.695L319.059 162.238C315.672 160.383 315.305 157.191 315.305 155.906C315.305 154.621 315.668 151.43 319.059 149.574V149.574ZM337.086 193.598C339.086 196.051 346.489 215.523 355.891 219.875V496.973H337.086V193.598ZM35.0317 454.715C35.0317 438.922 51.0356 424.055 75.8052 416.848C79.7895 415.688 82.0825 411.516 80.9224 407.531C79.7622 403.547 75.5942 401.258 71.606 402.418C56.3638 406.855 43.8989 413.766 35.0317 422.285V170.52C35.0317 147.613 68.3286 128.262 107.747 128.262C147.161 128.262 180.458 147.613 180.458 170.52V422.383C177.004 419.066 172.993 415.965 168.434 413.137C152.11 403.008 130.555 397.43 107.743 397.43C103.594 397.43 100.231 400.793 100.231 404.941C100.231 409.094 103.594 412.457 107.743 412.457C147.161 412.457 180.458 431.809 180.458 454.715C180.458 477.621 147.161 496.973 107.743 496.973C68.3286 496.973 35.0317 477.621 35.0317 454.715V454.715ZM168.434 496.293C185.879 485.473 195.485 470.707 195.485 454.715V183.973H322.059V496.973H167.286C167.668 496.746 168.059 496.527 168.434 496.293V496.293ZM416.641 474.215C416.641 486.762 406.434 496.973 393.887 496.973H370.918V222.762C377.704 221.715 383.532 217.664 386.922 211.469C386.922 211.469 393.887 193.91 404.583 186.641C411.911 190.551 416.641 198.246 416.641 206.727V474.215ZM468.958 458.805C473.797 458.805 477.735 462.742 477.735 467.582C477.735 472.422 473.797 476.359 468.958 476.359H431.606C431.645 475.652 431.668 458.805 431.668 458.805H468.958ZM468.958 395.25C473.797 395.25 477.735 399.187 477.735 404.027C477.735 408.867 473.797 412.805 468.958 412.805H431.668V395.25H468.958ZM468.958 331.691C473.797 331.691 477.735 335.629 477.735 340.473C477.735 345.313 473.797 349.25 468.958 349.25H431.668V331.695H468.958V331.691Z\" fill=\"#114A9F\"><\/path><\/svg>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"\/spezialreinigung#specialised_services\" >\n\t\t\t\t\t\t\tTeppich &amp; B\u00f6den\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2df5f63c elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"2df5f63c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"\/spezialreinigung#specialised_services\" class=\"elementor-icon elementor-animation-float\" tabindex=\"-1\" aria-label=\"Moos entfernen\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"512pt\" height=\"512pt\" viewBox=\"0 0 512 512\"><g id=\"#114a9fff\"><path fill=\"#114a9f\" opacity=\"1.00\" d=\" M 145.68 0.00 L 161.73 0.00 C 177.39 0.17 192.97 5.78 204.98 15.87 C 213.08 22.54 219.50 31.11 223.92 40.60 C 233.75 25.12 251.04 14.57 269.41 13.56 C 279.30 13.27 289.46 12.85 299.03 15.82 C 314.01 20.15 326.82 30.90 334.14 44.61 C 343.08 30.84 358.58 21.48 375.05 20.61 C 384.96 20.25 395.19 20.01 404.62 23.60 C 408.28 24.97 412.98 26.53 413.84 30.92 C 415.23 35.96 410.00 41.30 404.95 39.79 C 400.03 38.13 395.23 35.82 389.93 35.67 C 381.59 35.31 372.87 34.84 364.96 37.99 C 353.67 42.27 344.75 52.29 341.92 64.03 C 340.74 68.41 340.78 72.97 340.74 77.46 C 368.63 77.47 396.52 77.47 424.40 77.46 C 424.38 72.33 424.36 67.08 422.66 62.18 C 421.86 59.23 420.04 56.20 421.11 53.09 C 422.32 48.91 427.55 46.63 431.43 48.62 C 434.83 50.13 435.78 54.06 436.89 57.26 C 439.04 63.79 439.46 70.71 439.40 77.53 C 449.92 77.58 460.45 77.45 470.98 77.57 C 475.45 77.34 478.94 81.64 478.50 85.95 C 478.50 184.96 478.51 283.97 478.49 382.98 C 478.93 387.27 475.46 391.50 471.06 391.40 C 466.60 391.58 463.04 387.31 463.51 382.98 C 463.49 325.29 463.51 267.60 463.50 209.92 C 436.78 215.75 412.80 231.48 395.28 252.28 C 381.94 267.98 372.14 286.57 366.18 306.27 C 358.39 331.56 358.99 358.74 349.72 383.65 C 344.84 397.07 336.92 409.82 325.14 418.20 C 319.88 422.13 313.88 424.90 307.90 427.54 C 359.77 427.53 411.64 427.54 463.50 427.53 C 463.56 423.36 463.28 419.18 463.65 415.03 C 463.96 411.40 467.41 408.52 471.00 408.59 C 474.60 408.52 478.05 411.43 478.35 415.07 C 478.71 419.21 478.43 423.37 478.50 427.53 C 487.33 427.61 496.17 427.39 505.00 427.61 C 508.66 427.60 511.42 430.75 512.00 434.18 L 512.00 482.08 C 511.09 490.38 507.28 498.42 500.90 503.90 C 495.75 508.52 489.09 511.11 482.29 512.00 L 36.39 512.00 C 27.18 511.64 18.11 507.93 11.52 501.46 C 4.49 494.81 0.37 485.34 0.00 475.69 L 0.00 433.78 C 0.84 430.57 3.43 427.59 6.97 427.61 C 15.80 427.39 24.65 427.62 33.50 427.53 C 33.49 333.35 33.53 239.17 33.47 144.99 C 33.50 141.09 32.88 136.13 36.67 133.66 C 41.35 129.99 48.95 134.05 48.46 140.00 C 48.56 197.52 48.45 255.05 48.52 312.57 C 62.10 309.32 74.36 302.25 86.29 295.23 C 102.53 285.29 118.27 274.23 131.73 260.70 C 144.13 248.42 150.36 231.37 153.30 214.48 C 157.98 188.87 156.79 162.52 162.48 137.07 C 165.91 121.36 171.73 106.09 180.46 92.54 C 136.48 92.52 92.50 92.54 48.51 92.53 C 48.45 97.33 48.59 102.13 48.49 106.93 C 48.72 110.20 46.95 113.60 43.80 114.78 C 39.21 116.86 33.37 113.05 33.56 107.98 C 33.43 100.34 33.46 92.69 33.55 85.05 C 33.38 81.02 36.96 77.39 41.00 77.57 C 54.33 77.46 67.66 77.59 80.99 77.52 C 80.97 70.62 80.76 63.67 82.04 56.86 C 84.76 41.16 93.23 26.59 105.40 16.32 C 116.62 6.71 130.98 1.12 145.68 0.00 M 134.93 17.14 C 117.08 22.16 102.46 37.08 97.83 55.04 C 95.76 62.32 95.94 69.96 95.98 77.46 C 135.65 77.47 175.31 77.47 214.98 77.47 C 214.97 73.30 215.08 69.12 214.78 64.96 C 213.93 52.18 208.21 39.84 199.14 30.82 C 189.42 21.01 175.81 15.21 162.00 15.05 C 152.96 15.00 143.69 14.47 134.93 17.14 M 259.08 30.82 C 245.93 35.29 235.35 46.50 231.64 59.88 C 229.92 65.58 229.91 71.57 229.98 77.46 C 261.91 77.47 293.85 77.48 325.79 77.46 C 326.03 69.49 325.41 61.29 321.95 53.99 C 315.60 39.53 300.81 29.24 285.01 28.52 C 276.35 28.33 267.37 27.79 259.08 30.82 M 180.53 127.52 C 203.19 127.55 225.84 127.53 248.50 127.53 C 248.50 115.86 248.51 104.20 248.49 92.53 C 232.01 92.53 215.53 92.53 199.06 92.53 C 190.62 102.81 184.59 114.90 180.53 127.52 M 263.50 127.53 C 300.17 127.54 336.83 127.54 373.50 127.53 C 373.50 115.86 373.51 104.20 373.49 92.53 C 336.83 92.53 300.17 92.53 263.51 92.53 C 263.49 104.20 263.50 115.86 263.50 127.53 M 388.50 127.53 C 413.50 127.53 438.50 127.54 463.50 127.53 C 463.49 115.86 463.51 104.20 463.49 92.53 C 438.50 92.53 413.50 92.53 388.51 92.53 C 388.49 104.20 388.50 115.86 388.50 127.53 M 172.40 177.53 C 177.43 177.54 182.46 177.53 187.49 177.53 C 187.49 165.86 187.50 154.20 187.49 142.53 C 183.87 142.53 180.25 142.53 176.64 142.53 C 174.24 154.06 173.35 165.81 172.40 177.53 M 202.50 142.53 C 202.48 154.20 202.50 165.86 202.49 177.53 C 239.17 177.54 275.85 177.53 312.53 177.53 C 312.53 165.86 312.54 154.20 312.52 142.53 C 275.85 142.54 239.17 142.53 202.50 142.53 M 327.53 142.54 C 327.52 154.20 327.53 165.86 327.53 177.52 C 361.18 177.55 394.84 177.53 428.50 177.53 C 428.49 165.86 428.51 154.20 428.49 142.53 C 394.84 142.53 361.18 142.53 327.53 142.54 M 443.50 177.53 C 450.17 177.54 456.83 177.54 463.50 177.53 C 463.49 165.86 463.51 154.20 463.49 142.53 C 456.83 142.53 450.17 142.53 443.51 142.53 C 443.49 154.20 443.50 165.86 443.50 177.53 M 171.23 192.54 C 170.22 204.30 168.69 216.04 165.92 227.53 C 193.44 227.53 220.97 227.54 248.50 227.53 C 248.50 215.86 248.51 204.20 248.49 192.53 C 222.73 192.54 196.98 192.52 171.23 192.54 M 263.50 227.53 C 300.17 227.54 336.83 227.54 373.50 227.53 C 373.49 215.86 373.51 204.20 373.49 192.53 C 336.83 192.53 300.17 192.53 263.51 192.53 C 263.49 204.20 263.51 215.86 263.50 227.53 M 388.50 192.54 C 388.50 204.20 388.50 215.86 388.50 227.52 C 392.52 227.00 397.53 229.04 400.64 225.64 C 418.54 210.49 440.20 199.74 463.07 194.61 C 463.22 194.10 463.51 193.06 463.65 192.54 C 438.60 192.52 413.55 192.53 388.50 192.54 M 161.06 242.54 C 155.74 256.09 146.83 267.92 135.99 277.54 C 153.16 277.52 170.33 277.55 187.49 277.53 C 187.49 265.86 187.50 254.20 187.49 242.53 C 178.68 242.54 169.87 242.52 161.06 242.54 M 202.50 242.54 C 202.48 254.20 202.50 265.86 202.49 277.53 C 239.17 277.54 275.85 277.53 312.53 277.53 C 312.53 265.86 312.54 254.20 312.52 242.53 C 275.85 242.54 239.17 242.53 202.50 242.54 M 327.53 242.54 C 327.52 254.20 327.53 265.86 327.53 277.52 C 338.80 277.54 350.07 277.55 361.34 277.52 C 367.31 264.97 374.89 253.20 383.80 242.53 C 365.04 242.53 346.29 242.53 327.53 242.54 M 115.72 293.73 C 102.53 303.28 88.60 311.84 73.96 318.98 C 66.25 322.70 58.27 326.03 49.81 327.56 C 74.37 327.50 98.93 327.55 123.50 327.53 C 123.49 315.86 123.51 304.19 123.49 292.51 C 120.90 292.73 117.85 291.80 115.72 293.73 M 138.50 327.53 C 175.17 327.54 211.83 327.54 248.50 327.53 C 248.50 315.86 248.51 304.20 248.49 292.53 C 211.83 292.53 175.17 292.53 138.51 292.53 C 138.49 304.20 138.51 315.86 138.50 327.53 M 263.50 327.53 C 290.98 327.56 318.47 327.49 345.95 327.56 C 348.04 315.67 350.81 303.88 354.99 292.53 C 324.50 292.53 294.00 292.53 263.51 292.53 C 263.49 304.20 263.50 315.86 263.50 327.53 M 48.50 377.53 C 55.17 377.54 61.83 377.54 68.50 377.53 C 68.50 365.86 68.51 354.20 68.49 342.53 C 61.83 342.53 55.17 342.53 48.51 342.53 C 48.49 354.20 48.50 365.86 48.50 377.53 M 83.50 377.53 C 118.17 377.54 152.83 377.54 187.49 377.53 C 187.49 365.86 187.50 354.20 187.49 342.53 C 152.83 342.53 118.17 342.53 83.51 342.53 C 83.49 354.20 83.50 365.86 83.50 377.53 M 202.50 342.54 C 202.49 354.20 202.50 365.86 202.49 377.53 C 239.17 377.54 275.85 377.53 312.53 377.53 C 312.53 365.86 312.54 354.20 312.52 342.53 C 275.85 342.54 239.17 342.53 202.50 342.54 M 327.53 342.54 C 327.53 354.20 327.53 365.86 327.53 377.53 C 330.36 377.53 333.18 377.53 336.01 377.53 C 339.98 366.22 342.00 354.36 343.73 342.53 C 338.33 342.53 332.93 342.53 327.53 342.54 M 48.50 427.53 C 73.50 427.54 98.50 427.54 123.50 427.53 C 123.50 415.86 123.51 404.20 123.49 392.53 C 98.50 392.53 73.50 392.53 48.51 392.53 C 48.49 404.20 48.50 415.86 48.50 427.53 M 138.50 427.53 C 175.17 427.54 211.83 427.54 248.50 427.53 C 248.50 415.86 248.51 404.20 248.49 392.53 C 211.83 392.53 175.17 392.53 138.51 392.53 C 138.49 404.20 138.50 415.86 138.50 427.53 M 263.51 392.53 C 263.49 404.20 263.50 415.86 263.50 427.53 C 268.71 427.53 273.92 427.55 279.14 427.52 C 287.28 417.96 300.11 415.42 310.67 409.59 C 318.12 405.64 324.28 399.57 328.90 392.56 C 307.10 392.50 285.30 392.54 263.51 392.53 M 15.00 442.53 C 15.06 453.69 14.88 464.86 15.09 476.02 C 15.55 487.64 26.35 497.46 37.95 497.00 C 184.98 497.00 332.01 497.00 479.04 497.00 C 488.31 497.43 496.90 489.40 496.96 480.10 C 497.07 467.58 496.96 455.05 497.00 442.53 C 336.33 442.53 175.67 442.53 15.00 442.53 Z\"><\/path><\/g><\/svg>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"\/spezialreinigung#specialised_services\" >\n\t\t\t\t\t\t\tMoos entfernen\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6052e157\" data-id=\"6052e157\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e35de0a elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"4e35de0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"\/fenster-fassaden\/\" class=\"elementor-icon elementor-animation-float\" tabindex=\"-1\" aria-label=\"Fassaden- &amp; Fensterreinigung\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"512\" height=\"512\" viewBox=\"0 0 512 512\" fill=\"none\"><path d=\"M488 16H24C21.8783 16 19.8434 16.8429 18.3431 18.3431C16.8429 19.8434 16 21.8783 16 24V488C16 490.122 16.8429 492.157 18.3431 493.657C19.8434 495.157 21.8783 496 24 496H488C490.122 496 492.157 495.157 493.657 493.657C495.157 492.157 496 490.122 496 488V24C496 21.8783 495.157 19.8434 493.657 18.3431C492.157 16.8429 490.122 16 488 16V16ZM72 72.45C98.289 75.396 122.95 92.82 142.152 122.262C162.752 153.85 174.612 195.403 175.881 240.003C170.329 240.038 164.96 241.994 160.687 245.538C156.414 249.083 153.499 253.997 152.439 259.447C144.541 254.192 138.614 246.461 135.59 237.47C135.059 235.877 134.041 234.491 132.678 233.509C131.316 232.527 129.679 231.998 128 231.998C126.321 231.998 124.684 232.527 123.322 233.509C121.959 234.491 120.941 235.877 120.41 237.47C118.305 243.736 114.777 249.429 110.103 254.103C105.429 258.778 99.7359 262.306 93.47 264.411C91.8774 264.942 90.4923 265.961 89.5108 267.323C88.5294 268.685 88.0012 270.321 88.0012 272C88.0012 273.679 88.5294 275.315 89.5108 276.677C90.4923 278.039 91.8774 279.058 93.47 279.589C99.7359 281.694 105.429 285.222 110.103 289.897C114.777 294.571 118.305 300.264 120.41 306.53C120.941 308.123 121.959 309.509 123.322 310.491C124.684 311.473 126.321 312.002 128 312.002C129.679 312.002 131.316 311.473 132.678 310.491C134.041 309.509 135.059 308.123 135.59 306.53C138.614 297.539 144.541 289.808 152.439 284.553C153.24 288.657 155.097 292.482 157.825 295.65C160.554 298.819 164.06 301.222 168 302.624V328C168 330.122 168.843 332.157 170.343 333.657C171.843 335.157 173.878 336 176 336H243.056L256.845 363.578C257.509 364.907 258.531 366.024 259.794 366.805C261.058 367.586 262.514 368 264 368V440H72V72.45ZM268.944 352L260.944 336H315.056L307.056 352H268.944ZM400 256C402.121 256.002 404.154 256.846 405.654 258.346C407.154 259.846 407.998 261.879 408 264V280C407.998 282.121 407.154 284.154 405.654 285.654C404.154 287.154 402.121 287.998 400 288H176C173.879 287.998 171.846 287.154 170.346 285.654C168.846 284.154 168.002 282.121 168 280V264C168.002 261.879 168.846 259.846 170.346 258.346C171.846 256.846 173.879 256.002 176 256H400ZM184 304H392V320H184V304ZM312 368C313.486 368 314.942 367.586 316.206 366.805C317.469 366.024 318.491 364.907 319.155 363.578L332.944 336H400C402.122 336 404.157 335.157 405.657 333.657C407.157 332.157 408 330.122 408 328V302.624C412.676 300.965 416.723 297.9 419.588 293.849C422.452 289.799 423.994 284.961 424 280V264C423.993 257.637 421.462 251.537 416.962 247.038C412.463 242.538 406.363 240.007 400 240H399.884C399.285 213.358 394.762 186.951 386.461 161.628C391.592 164.109 396.177 167.589 399.946 171.865C403.715 176.141 406.592 181.126 408.41 186.528C408.941 188.121 409.959 189.507 411.322 190.489C412.684 191.471 414.321 192 416 192C417.679 192 419.316 191.471 420.678 190.489C422.041 189.507 423.059 188.121 423.59 186.528C426.556 177.707 432.317 170.094 440 164.843V440H312V368ZM401.567 152C407.177 148.061 412.061 143.178 416 137.568C419.939 143.178 424.823 148.061 430.433 152C424.823 155.939 419.939 160.822 416 166.432C412.061 160.822 407.177 155.939 401.567 152V152ZM440 139.157C432.317 133.906 426.555 126.292 423.59 117.47C423.059 115.877 422.041 114.491 420.678 113.509C419.316 112.527 417.679 111.998 416 111.998C414.321 111.998 412.684 112.527 411.322 113.509C409.959 114.491 408.941 115.877 408.41 117.47C406.305 123.736 402.777 129.429 398.103 134.103C393.429 138.778 387.736 142.306 381.47 144.411C381.02 144.563 380.585 144.755 380.17 144.985C375.572 134.026 370.01 123.497 363.55 113.522C351.92 95.683 338.357 81.712 323.54 72H440V139.157ZM350.152 122.257C370.752 153.85 382.617 195.4 383.887 240H191.893C190.604 192.31 177.815 147.657 155.554 113.522C143.92 95.683 130.357 81.712 115.54 72H272C301.259 72 329.014 89.85 350.152 122.262V122.257ZM142.433 272C136.823 275.939 131.939 280.822 128 286.432C124.061 280.822 119.177 275.939 113.567 272C119.177 268.061 124.061 263.178 128 257.568C131.939 263.178 136.823 268.061 142.433 272ZM280 368H296V480H280V368ZM480 480H312V456H448C450.122 456 452.157 455.157 453.657 453.657C455.157 452.157 456 450.122 456 448V64C456 61.8783 455.157 59.8434 453.657 58.3431C452.157 56.8429 450.122 56 448 56H64C61.8783 56 59.8434 56.8429 58.3431 58.3431C56.8429 59.8434 56 61.8783 56 64V448C56 450.122 56.8429 452.157 58.3431 453.657C59.8434 455.157 61.8783 456 64 456H264V480H32V32H480V480Z\" fill=\"#114A9F\"><\/path><path d=\"M192 120H200V128C200 130.122 200.843 132.157 202.343 133.657C203.843 135.157 205.878 136 208 136C210.122 136 212.157 135.157 213.657 133.657C215.157 132.157 216 130.122 216 128V120H224C226.122 120 228.157 119.157 229.657 117.657C231.157 116.157 232 114.122 232 112C232 109.878 231.157 107.843 229.657 106.343C228.157 104.843 226.122 104 224 104H216V96C216 93.8783 215.157 91.8434 213.657 90.3431C212.157 88.8429 210.122 88 208 88C205.878 88 203.843 88.8429 202.343 90.3431C200.843 91.8434 200 93.8783 200 96V104H192C189.878 104 187.843 104.843 186.343 106.343C184.843 107.843 184 109.878 184 112C184 114.122 184.843 116.157 186.343 117.657C187.843 119.157 189.878 120 192 120Z\" fill=\"#114A9F\"><\/path><path d=\"M304 208H312V216C312 218.122 312.843 220.157 314.343 221.657C315.843 223.157 317.878 224 320 224C322.122 224 324.157 223.157 325.657 221.657C327.157 220.157 328 218.122 328 216V208H336C338.122 208 340.157 207.157 341.657 205.657C343.157 204.157 344 202.122 344 200C344 197.878 343.157 195.843 341.657 194.343C340.157 192.843 338.122 192 336 192H328V184C328 181.878 327.157 179.843 325.657 178.343C324.157 176.843 322.122 176 320 176C317.878 176 315.843 176.843 314.343 178.343C312.843 179.843 312 181.878 312 184V192H304C301.878 192 299.843 192.843 298.343 194.343C296.843 195.843 296 197.878 296 200C296 202.122 296.843 204.157 298.343 205.657C299.843 207.157 301.878 208 304 208Z\" fill=\"#114A9F\"><\/path><\/svg>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"\/fenster-fassaden\/\" >\n\t\t\t\t\t\t\tFassaden- &amp; Fensterreinigung\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31078c8 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"31078c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"\/spezialreinigung#specialised_services\" class=\"elementor-icon elementor-animation-float\" tabindex=\"-1\" aria-label=\"Marmor Kristallisation\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"512\" height=\"512\" viewBox=\"0 0 512 512\" fill=\"none\"><path d=\"M422.678 203.544L387.768 168.637L388.919 163.807L427.092 152.514C429.991 151.658 431.985 148.992 431.985 145.968C431.985 142.943 429.991 140.278 427.092 139.421L388.919 128.128L380.599 93.1873C379.865 90.1101 377.119 87.941 373.958 87.941C370.797 87.941 368.051 90.1101 367.318 93.1873L359.004 128.128L349.942 130.809L295.417 76.2913C285.338 66.2083 271.93 60.6548 257.678 60.6548C243.419 60.6548 230.018 66.2083 219.938 76.2913L92.679 203.544C71.8662 224.353 71.8662 258.22 92.679 279.03L99.0517 285.402L91.5577 311.999C87.6238 332.709 63.565 368.319 63.3243 368.676C61.4845 371.386 61.8242 375.023 64.1435 377.339L139.838 453.033C141.157 454.352 142.904 455.033 144.664 455.033C145.944 455.033 147.238 454.673 148.371 453.936L189.044 427.609C199.489 420.847 209.488 413.38 219.063 405.41L219.937 406.282C230.016 416.365 243.417 421.915 257.676 421.915C271.93 421.915 285.336 416.365 295.416 406.282L422.675 279.03C443.484 258.217 443.484 224.357 422.678 203.544V203.544ZM366.664 140.1C369.011 139.407 370.804 137.513 371.371 135.134L373.958 124.257L376.552 135.134C377.119 137.515 378.913 139.407 381.259 140.1L401.092 145.968L381.259 151.835C378.913 152.528 377.119 154.422 376.552 156.802L373.958 167.678L371.371 156.802C370.804 154.421 369.011 152.528 366.664 151.835L346.831 145.968L366.664 140.1ZM181.624 416.15L145.591 439.477L77.7303 371.616C84.7566 360.7 101.371 333.472 104.837 315.126L133.944 211.813C135.085 205.826 140.397 201.712 146.584 202.32C149.738 202.62 152.578 204.139 154.578 206.6C156.505 208.968 157.418 211.92 157.165 214.948L143.592 273.768C142.913 276.738 144.272 279.798 146.939 281.274C149.586 282.75 152.912 282.288 155.073 280.13L253.08 182.127C256.9 178.311 263.52 178.323 267.327 182.127C269.227 184.03 270.28 186.561 270.28 189.25C270.28 191.944 269.227 194.475 267.327 196.377C267.327 196.377 267.327 196.379 267.326 196.379L195.221 268.488C192.555 271.153 192.555 275.475 195.221 278.14C197.886 280.806 202.208 280.806 204.874 278.14L296.9 186.11C300.834 182.183 307.221 182.183 311.155 186.11C313.054 188.013 314.102 190.544 314.102 193.237C314.102 195.927 313.056 198.458 311.155 200.361L287.101 224.413C287.097 224.416 287.092 224.42 287.087 224.423L219.121 292.389C216.455 295.055 216.455 299.376 219.121 302.042C220.454 303.375 222.201 304.042 223.947 304.042C225.693 304.042 227.441 303.375 228.774 302.042L296.749 234.071C300.763 230.064 307.291 230.065 311.315 234.076C315.329 238.094 315.329 244.633 311.315 248.649L291.716 268.249L239.683 320.278C237.017 322.944 237.017 327.265 239.683 329.931C242.349 332.597 246.67 332.597 249.336 329.931L252.993 326.274C252.996 326.27 253 326.27 253.002 326.267L301.368 277.9C305.082 274.183 311.569 274.172 315.295 277.903C317.155 279.76 318.181 282.233 318.181 284.863C318.181 287.493 317.153 289.966 315.295 291.826L230.494 376.629C215.665 391.456 199.224 404.753 181.624 416.15V416.15ZM413.024 269.377L285.764 396.629C278.259 404.132 268.285 408.262 257.678 408.262C247.064 408.262 237.092 404.132 229.591 396.626L229.422 396.457C233.069 393.141 236.664 389.768 240.145 386.285L324.946 301.482C329.387 297.042 331.832 291.142 331.832 284.866C331.832 278.586 329.385 272.686 324.946 268.254C322.483 265.786 319.49 264.076 316.292 262.978L320.966 258.304C330.307 248.963 330.307 233.764 320.966 224.42C318.346 221.805 315.247 220.001 311.967 218.853L320.806 210.014C325.286 205.534 327.752 199.574 327.752 193.237C327.752 186.897 325.286 180.937 320.806 176.454C311.532 167.197 296.493 167.214 287.246 176.457L282.459 181.244C281.315 178.046 279.537 175.029 276.98 172.474C268.027 163.51 252.394 163.497 243.427 172.474L162.255 253.646L170.575 217.59C170.634 217.33 170.675 217.069 170.708 216.81C171.46 209.993 169.501 203.31 165.175 197.987C160.848 192.667 154.708 189.377 147.881 188.726C134.707 187.486 122.995 196.306 120.668 208.686L103.3 270.339L102.335 269.375C86.849 253.885 86.849 228.685 102.335 213.195L229.595 85.9425C237.095 78.44 247.067 74.3064 257.681 74.3064C268.288 74.3064 278.262 78.44 285.768 85.9425L335.044 135.214L320.828 139.419C317.928 140.276 315.935 142.942 315.935 145.966C315.935 148.99 317.928 151.656 320.828 152.513L359.008 163.806L367.321 198.746C368.055 201.823 370.801 203.993 373.962 203.993C377.122 203.993 379.868 201.823 380.602 198.746L384.058 184.229L413.029 213.197C428.505 228.686 428.505 253.887 413.024 269.377Z\" fill=\"#114A9F\"><\/path><path d=\"M100.665 84.2735C104.438 84.2735 107.491 81.2168 107.491 77.4468V63.7935C107.491 60.0234 104.438 56.9668 100.665 56.9668C96.8911 56.9668 93.8379 60.0234 93.8379 63.7935V77.4468C93.8379 81.2168 96.8911 84.2735 100.665 84.2735Z\" fill=\"#114A9F\"><\/path><path d=\"M100.665 97.9268C96.8911 97.9268 93.8379 100.983 93.8379 104.753V118.407C93.8379 122.177 96.8911 125.233 100.665 125.233C104.438 125.233 107.491 122.177 107.491 118.407V104.753C107.491 100.983 104.438 97.9268 100.665 97.9268V97.9268Z\" fill=\"#114A9F\"><\/path><path d=\"M73.3579 97.9268H87.0113C90.7847 97.9268 93.8379 94.8701 93.8379 91.1001C93.8379 87.3301 90.7847 84.2734 87.0113 84.2734H73.3579C69.5845 84.2734 66.5312 87.3301 66.5312 91.1001C66.5312 94.8701 69.5845 97.9268 73.3579 97.9268Z\" fill=\"#114A9F\"><\/path><path d=\"M114.318 97.9268H127.971C131.745 97.9268 134.798 94.8701 134.798 91.1001C134.798 87.3301 131.745 84.2734 127.971 84.2734H114.318C110.544 84.2734 107.491 87.3301 107.491 91.1001C107.491 94.8701 110.544 97.9268 114.318 97.9268Z\" fill=\"#114A9F\"><\/path><path d=\"M390.798 391.474C377.624 391.474 366.904 402.193 366.904 415.367C366.904 428.541 377.624 439.26 390.798 439.26C403.971 439.26 414.691 428.541 414.691 415.367C414.691 402.193 403.971 391.474 390.798 391.474V391.474ZM390.798 425.607C385.15 425.607 380.558 421.014 380.558 415.367C380.558 409.72 385.15 405.127 390.798 405.127C396.445 405.127 401.038 409.72 401.038 415.367C401.038 421.014 396.443 425.607 390.798 425.607Z\" fill=\"#114A9F\"><\/path><path d=\"M442.557 347.296C438.526 347.296 435.26 350.565 435.26 354.594C435.26 358.625 438.526 361.893 442.557 361.893C446.589 361.893 449.855 358.625 449.855 354.594C449.857 350.563 446.589 347.296 442.557 347.296Z\" fill=\"#114A9F\"><\/path><\/svg>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"\/spezialreinigung#specialised_services\" >\n\t\t\t\t\t\t\tMarmor Kristallisation\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65448861 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"65448861\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<a href=\"\/baureinigung\/\" class=\"elementor-icon elementor-animation-float\" tabindex=\"-1\" aria-label=\"Baureinigung\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"512\" height=\"512\" viewBox=\"0 0 512 512\" fill=\"none\"><path d=\"M111.496 480H40.0002C37.8784 480 35.8436 479.157 34.3433 477.657C32.843 476.156 32.0002 474.122 32.0002 472C32.0033 470.571 32.3941 469.17 33.1309 467.945C33.8677 466.721 34.923 465.72 36.1842 465.048C37.3147 464.429 38.279 463.546 38.995 462.475C39.711 461.403 40.1575 460.175 40.2966 458.893C40.4356 457.612 40.2631 456.316 39.7936 455.116C39.3241 453.916 38.5716 452.847 37.6002 452C35.8525 450.525 34.4464 448.688 33.4794 446.616C32.5124 444.544 32.0077 442.287 32.0002 440C32.0186 435.918 33.6002 431.999 36.4197 429.047C39.2392 426.096 43.0823 424.337 47.1588 424.132C51.2353 423.927 55.2355 425.292 58.3367 427.946C61.4379 430.6 63.4045 434.341 63.8322 438.4C63.9423 438.926 63.9986 439.462 64.0002 440C64.0002 442.122 64.843 444.156 66.3433 445.657C67.8436 447.157 69.8784 448 72.0002 448C75.158 448.005 78.2401 448.968 80.8402 450.76C81.709 451.351 82.6857 451.765 83.7146 451.978C84.7434 452.192 85.8042 452.201 86.8364 452.004C87.8686 451.808 88.852 451.41 89.7305 450.833C90.6089 450.257 91.3652 449.513 91.9562 448.644C92.5471 447.775 92.9612 446.798 93.1746 445.77C93.3881 444.741 93.3969 443.68 93.2004 442.648C93.0039 441.615 92.606 440.632 92.0295 439.754C91.4529 438.875 90.709 438.119 89.8402 437.528C86.5757 435.298 82.9239 433.698 79.0722 432.808C77.3243 425.146 72.8127 418.397 66.4006 413.854C59.9885 409.31 52.1261 407.29 44.3179 408.18C36.5097 409.071 29.3039 412.809 24.0793 418.679C18.8547 424.55 15.9782 432.141 16.0002 440C16.0079 446.125 17.792 452.116 21.1362 457.248C18.3511 460.782 16.6184 465.029 16.137 469.503C15.6555 473.976 16.4447 478.495 18.414 482.54C20.3833 486.586 23.453 489.995 27.271 492.375C31.0891 494.756 35.5008 496.012 40.0002 496H111.496C113.618 496 115.653 495.157 117.153 493.657C118.653 492.156 119.496 490.122 119.496 488C119.496 485.878 118.653 483.843 117.153 482.343C115.653 480.843 113.618 480 111.496 480Z\" fill=\"#114A9F\"><\/path><path d=\"M307.576 480.84L284.376 469.248C273.422 463.815 264.208 455.423 257.779 445.022C251.35 434.621 247.962 422.627 248 410.4C248.044 398.288 245.157 386.345 239.584 375.59C234.012 364.836 225.92 355.589 216 348.64V320C216 313.635 213.471 307.53 208.971 303.029C204.47 298.529 198.365 296 192 296H168V40C168 37.8783 168.843 35.8434 170.343 34.3431C171.843 32.8429 173.878 32 176 32C178.122 32 180.157 32.8429 181.657 34.3431C183.157 35.8434 184 37.8783 184 40V272C184 274.122 184.843 276.157 186.343 277.657C187.843 279.157 189.878 280 192 280C194.122 280 196.157 279.157 197.657 277.657C199.157 276.157 200 274.122 200 272V40C200 33.6348 197.471 27.5303 192.971 23.0294C188.47 18.5286 182.365 16 176 16C169.635 16 163.53 18.5286 159.029 23.0294C154.529 27.5303 152 33.6348 152 40V297.472C147.337 299.121 143.297 302.17 140.433 306.202C137.569 310.235 136.02 315.054 136 320V348.328C126.577 354.578 118.76 362.963 113.184 372.8C106.559 384.969 103.405 398.725 104.067 412.566C104.728 426.406 109.18 439.798 116.936 451.28C117.463 452.222 118.175 453.048 119.03 453.708C119.885 454.368 120.864 454.847 121.91 455.119C122.955 455.39 124.044 455.446 125.112 455.285C126.179 455.124 127.203 454.749 128.122 454.181C129.041 453.614 129.835 452.866 130.457 451.984C131.079 451.101 131.516 450.102 131.741 449.046C131.967 447.99 131.977 446.899 131.769 445.84C131.562 444.78 131.143 443.773 130.536 442.88C125.625 435.472 122.362 427.096 120.966 418.318C119.571 409.541 120.076 400.566 122.448 392H152V408C152 410.122 152.843 412.157 154.343 413.657C155.843 415.157 157.878 416 160 416C162.122 416 164.157 415.157 165.657 413.657C167.157 412.157 168 410.122 168 408V392H184V408C184 410.122 184.843 412.157 186.343 413.657C187.843 415.157 189.878 416 192 416C194.122 416 196.157 415.157 197.657 413.657C199.157 412.157 200 410.122 200 408V392H229.104C231.016 397.946 231.993 404.154 232 410.4C231.957 424.184 235.422 437.753 242.068 449.829C248.715 461.906 258.324 472.093 269.992 479.432C257.972 478.215 246.382 474.296 236.089 467.969C225.796 461.643 217.066 453.071 210.552 442.896C209.394 441.19 207.621 439.998 205.605 439.567C203.589 439.137 201.484 439.501 199.73 440.584C197.976 441.668 196.708 443.387 196.19 445.382C195.673 447.378 195.945 449.497 196.952 451.296C203.589 461.984 212.355 471.191 222.704 478.344C212.057 476.298 201.941 472.099 192.976 466.003C184.01 459.908 176.385 452.044 170.568 442.896C169.41 441.19 167.637 439.998 165.621 439.567C163.605 439.137 161.5 439.501 159.746 440.584C157.992 441.668 156.724 443.387 156.206 445.382C155.689 447.378 155.962 449.497 156.968 451.296C163.633 461.985 172.436 471.18 182.824 478.304C170.505 475.893 158.902 470.694 148.904 463.104C148.07 462.464 147.119 461.995 146.104 461.723C145.089 461.451 144.03 461.381 142.988 461.518C141.946 461.655 140.942 461.996 140.032 462.522C139.121 463.047 138.324 463.746 137.684 464.58C137.044 465.414 136.575 466.365 136.303 467.38C136.031 468.395 135.961 469.454 136.098 470.496C136.235 471.538 136.576 472.542 137.102 473.452C137.627 474.362 138.326 475.16 139.16 475.8C156.52 488.953 177.716 496.049 199.496 496H304C305.818 496.02 307.59 495.421 309.022 494.3C310.454 493.178 311.461 491.603 311.877 489.833C312.294 488.062 312.095 486.203 311.313 484.561C310.531 482.919 309.213 481.592 307.576 480.8V480.84ZM152 320C152 317.878 152.843 315.843 154.343 314.343C155.843 312.843 157.878 312 160 312H192C194.122 312 196.157 312.843 197.657 314.343C199.157 315.843 200 317.878 200 320V340.344C192.443 337.536 184.454 336.066 176.392 336H176C167.814 336.049 159.696 337.499 152 340.288V320ZM130.16 376C135.307 368.608 142.162 362.566 150.142 358.388C158.122 354.21 166.992 352.019 176 352H176.304C185.147 352.123 193.832 354.366 201.628 358.543C209.423 362.719 216.103 368.706 221.104 376H130.16Z\" fill=\"#114A9F\"><\/path><path d=\"M471.144 448H467.608C464.808 443.151 460.785 439.121 455.941 436.314C451.096 433.506 445.6 432.019 440 432C435.554 431.998 431.158 432.942 427.104 434.768C423.621 432.989 419.76 432.077 415.85 432.109C411.939 432.141 408.093 433.116 404.64 434.952L405.768 422.048C406.872 422.088 408.024 422.256 409.112 422.256C411.149 422.256 413.152 422.176 415.12 422.016C431.92 420.656 444.128 413.576 449.408 402.104C458.688 381.936 443.48 355.416 413.104 337.648L416 304.688C416.095 303.546 415.939 302.396 415.544 301.32C415.854 299.564 416.006 297.784 416 296C415.987 290.342 414.472 284.789 411.608 279.908C408.745 275.028 404.637 270.996 399.704 268.224C398.996 263.831 397.084 259.719 394.181 256.347C391.277 252.975 387.496 250.473 383.256 249.12C381.872 242.796 378.598 237.042 373.868 232.622C369.139 228.201 363.177 225.323 356.774 224.368C350.371 223.414 343.829 224.428 338.016 227.277C332.203 230.126 327.393 234.675 324.224 240.32C322.825 240.117 321.414 240.01 320 240C312.763 240.013 305.745 242.479 300.09 246.995C294.435 251.511 290.478 257.81 288.864 264.864C288.112 265.04 287.4 265.32 286.672 265.552C283.721 262.529 280.195 260.127 276.301 258.486C272.407 256.846 268.225 256.001 264 256C257.814 255.984 251.756 257.766 246.564 261.13C241.372 264.494 237.27 269.295 234.757 274.948C232.244 280.601 231.428 286.862 232.408 292.97C233.389 299.079 236.124 304.77 240.28 309.352C240.392 309.472 240.552 309.512 240.664 309.632L254.672 417.032C254.923 418.958 255.865 420.727 257.324 422.009C258.783 423.291 260.658 423.999 262.6 424C262.951 424.003 263.301 423.981 263.648 423.936C265.75 423.659 267.657 422.559 268.948 420.878C270.24 419.196 270.811 417.071 270.536 414.968L257.112 312H268.448C270.793 316.124 274.035 319.668 277.933 322.372C281.831 325.075 286.287 326.869 290.971 327.62C295.655 328.371 300.448 328.06 304.996 326.711C309.544 325.362 313.731 323.008 317.248 319.824C320.62 320.235 324.04 319.925 327.283 318.915C330.526 317.906 333.518 316.219 336.061 313.967C338.604 311.715 340.64 308.949 342.034 305.852C343.428 302.755 344.149 299.397 344.149 296C344.149 292.604 343.428 289.246 342.034 286.148C340.64 283.051 338.604 280.285 336.061 278.033C333.518 275.781 330.526 274.095 327.283 273.085C324.04 272.075 320.62 271.766 317.248 272.176C313.861 269.171 309.871 266.926 305.544 265.592C307.228 261.845 310.283 258.884 314.081 257.319C317.88 255.754 322.133 255.703 325.968 257.176C327.016 257.597 328.141 257.792 329.27 257.747C330.399 257.702 331.505 257.418 332.516 256.915C333.527 256.412 334.42 255.7 335.137 254.827C335.853 253.953 336.376 252.938 336.672 251.848C337.697 248.136 340.031 244.92 343.243 242.794C346.454 240.668 350.326 239.775 354.144 240.281C357.962 240.787 361.468 242.658 364.015 245.547C366.562 248.436 367.977 252.149 368 256C368 258.122 368.843 260.157 370.343 261.657C371.844 263.157 373.878 264 376 264C378.093 264 380.103 264.82 381.598 266.284C383.094 267.748 383.956 269.74 384 271.832L383.888 272.776C383.744 274.543 384.19 276.308 385.157 277.794C386.124 279.279 387.558 280.402 389.232 280.984C392.359 282.066 395.074 284.091 397.003 286.781C398.931 289.47 399.979 292.691 400 296H365.784C363.662 296 361.628 296.843 360.127 298.343C358.627 299.844 357.784 301.878 357.784 304C357.784 306.122 358.627 308.157 360.127 309.657C361.628 311.157 363.662 312 365.784 312H399.272L396.72 341.376L391.28 403.904C384.75 402.372 378.388 400.196 372.288 397.408C342.312 383.608 327.584 360.608 333.088 348.552C333.975 346.625 334.06 344.424 333.324 342.434C332.588 340.443 331.092 338.827 329.164 337.94C327.237 337.053 325.036 336.969 323.045 337.704C321.055 338.44 319.439 339.937 318.552 341.864C308.232 364.264 328.88 395.056 365.56 411.936C373.345 415.512 381.501 418.216 389.88 420L387.576 446.584C385.18 447.493 382.643 447.972 380.08 448H376C367.513 448 359.374 451.372 353.373 457.373C347.372 463.374 344 471.513 344 480V488C344 490.122 344.843 492.157 346.343 493.657C347.844 495.157 349.878 496 352 496H392C394.122 496 396.157 495.157 397.657 493.657C399.157 492.157 400 490.122 400 488C400 485.878 399.157 483.844 397.657 482.343C396.157 480.843 394.122 480 392 480H360C360 475.757 361.686 471.687 364.686 468.687C367.687 465.686 371.757 464 376 464H380.08C385.782 463.857 391.398 462.575 396.597 460.228C401.796 457.881 406.473 454.518 410.352 450.336C411.79 448.884 413.736 448.047 415.78 448.002C417.823 447.957 419.804 448.708 421.304 450.096C422.635 451.292 424.328 452.008 426.114 452.128C427.899 452.248 429.673 451.767 431.152 450.76C433.758 448.975 436.841 448.013 440 448C443.295 448.02 446.502 449.057 449.186 450.968C451.869 452.88 453.897 455.573 454.992 458.68C455.545 460.236 456.567 461.583 457.916 462.536C459.265 463.488 460.876 464 462.528 464H471.144C473.138 463.927 475.095 464.543 476.687 465.745C478.278 466.948 479.406 468.663 479.88 470.6C480.085 471.752 480.035 472.934 479.733 474.064C479.431 475.193 478.886 476.243 478.134 477.14C477.383 478.036 476.445 478.756 475.385 479.251C474.325 479.745 473.17 480.001 472 480H424C421.878 480 419.844 480.843 418.343 482.343C416.843 483.844 416 485.878 416 488C416 490.122 416.843 492.157 418.343 493.657C419.844 495.157 421.878 496 424 496H472C475.492 496.002 478.942 495.243 482.109 493.774C485.277 492.306 488.086 490.164 490.341 487.498C492.596 484.832 494.242 481.706 495.164 478.339C496.086 474.971 496.262 471.443 495.68 468C494.585 462.319 491.527 457.203 487.042 453.547C482.557 449.891 476.93 447.928 471.144 448V448ZM250.272 296C248.786 293.597 247.999 290.826 248 288C248 283.757 249.686 279.687 252.686 276.687C255.687 273.686 259.757 272 264 272C266.995 272.026 269.92 272.906 272.432 274.536C267.032 280.382 264.023 288.042 264 296H250.272ZM317.296 288.528C318.159 288.195 319.075 288.016 320 288C322.122 288 324.157 288.843 325.657 290.343C327.157 291.844 328 293.878 328 296C328 298.122 327.157 300.157 325.657 301.657C324.157 303.157 322.122 304 320 304C319.075 303.985 318.159 303.806 317.296 303.472C315.732 302.911 314.032 302.85 312.432 303.299C310.832 303.748 309.412 304.683 308.368 305.976C306.891 307.82 305.022 309.311 302.897 310.342C300.772 311.374 298.444 311.92 296.082 311.94C293.72 311.96 291.383 311.455 289.24 310.46C287.098 309.465 285.204 308.006 283.695 306.188C282.186 304.37 281.101 302.24 280.518 299.951C279.935 297.662 279.868 295.272 280.323 292.954C280.778 290.636 281.744 288.448 283.149 286.549C284.554 284.651 286.364 283.089 288.448 281.976H288.512C291.763 280.189 295.546 279.619 299.179 280.37C302.813 281.121 306.06 283.142 308.336 286.072C309.388 287.363 310.817 288.294 312.423 288.734C314.029 289.174 315.733 289.102 317.296 288.528ZM434.896 395.416C432.602 398.854 429.459 401.642 425.772 403.509C422.084 405.376 417.977 406.259 413.848 406.072C411.626 406.192 409.398 406.192 407.176 406.072L411.56 355.672C429.6 368.312 439.768 384.8 434.872 395.416H434.896Z\" fill=\"#114A9F\"><\/path><path d=\"M424 248C428.747 248 433.387 246.592 437.334 243.955C441.28 241.318 444.357 237.57 446.173 233.184C447.99 228.799 448.465 223.973 447.539 219.318C446.613 214.662 444.327 210.386 440.971 207.029C437.614 203.673 433.338 201.387 428.682 200.461C424.027 199.535 419.201 200.01 414.816 201.827C410.43 203.643 406.682 206.72 404.045 210.666C401.408 214.613 400 219.253 400 224C400 230.365 402.529 236.47 407.029 240.971C411.53 245.471 417.635 248 424 248V248ZM424 216C425.582 216 427.129 216.469 428.445 217.348C429.76 218.227 430.786 219.477 431.391 220.939C431.997 222.4 432.155 224.009 431.846 225.561C431.538 227.113 430.776 228.538 429.657 229.657C428.538 230.776 427.113 231.538 425.561 231.846C424.009 232.155 422.4 231.997 420.939 231.391C419.477 230.786 418.227 229.76 417.348 228.445C416.469 227.129 416 225.582 416 224C416 221.878 416.843 219.843 418.343 218.343C419.843 216.843 421.878 216 424 216Z\" fill=\"#114A9F\"><\/path><path d=\"M472 304C476.747 304 481.387 302.592 485.334 299.955C489.28 297.318 492.357 293.57 494.173 289.184C495.99 284.799 496.465 279.973 495.539 275.318C494.613 270.662 492.327 266.386 488.971 263.029C485.614 259.673 481.338 257.387 476.682 256.461C472.027 255.535 467.201 256.01 462.816 257.827C458.43 259.643 454.682 262.72 452.045 266.666C449.408 270.613 448 275.253 448 280C448 286.365 450.529 292.47 455.029 296.971C459.53 301.471 465.635 304 472 304V304ZM472 272C473.582 272 475.129 272.469 476.445 273.348C477.76 274.227 478.786 275.477 479.391 276.939C479.997 278.4 480.155 280.009 479.846 281.561C479.538 283.113 478.776 284.538 477.657 285.657C476.538 286.776 475.113 287.538 473.561 287.846C472.009 288.155 470.4 287.997 468.939 287.391C467.477 286.786 466.227 285.76 465.348 284.445C464.469 283.129 464 281.582 464 280C464 277.878 464.843 275.843 466.343 274.343C467.843 272.843 469.878 272 472 272Z\" fill=\"#114A9F\"><\/path><path d=\"M40 368C40 372.747 41.4076 377.387 44.0447 381.334C46.6819 385.28 50.4302 388.357 54.8156 390.173C59.201 391.99 64.0266 392.465 68.6822 391.539C73.3377 390.613 77.6141 388.327 80.9706 384.971C84.327 381.614 86.6128 377.338 87.5388 372.682C88.4649 368.027 87.9896 363.201 86.1731 358.816C84.3566 354.43 81.2805 350.682 77.3337 348.045C73.3869 345.408 68.7468 344 64 344C57.6348 344 51.5303 346.529 47.0294 351.029C42.5286 355.53 40 361.635 40 368ZM72 368C72 369.582 71.5308 371.129 70.6518 372.445C69.7727 373.76 68.5233 374.786 67.0615 375.391C65.5997 375.997 63.9911 376.155 62.4393 375.846C60.8874 375.538 59.462 374.776 58.3431 373.657C57.2243 372.538 56.4624 371.113 56.1537 369.561C55.845 368.009 56.0035 366.4 56.609 364.939C57.2145 363.477 58.2398 362.227 59.5554 361.348C60.871 360.469 62.4177 360 64 360C66.1217 360 68.1566 360.843 69.6569 362.343C71.1571 363.843 72 365.878 72 368Z\" fill=\"#114A9F\"><\/path><path d=\"M40 328C44.7468 328 49.3869 326.592 53.3337 323.955C57.2805 321.318 60.3566 317.57 62.1731 313.184C63.9896 308.799 64.4649 303.973 63.5388 299.318C62.6128 294.662 60.327 290.386 56.9706 287.029C53.6141 283.673 49.3377 281.387 44.6822 280.461C40.0266 279.535 35.201 280.01 30.8156 281.827C26.4302 283.643 22.6819 286.72 20.0447 290.666C17.4076 294.613 16 299.253 16 304C16 310.365 18.5286 316.47 23.0294 320.971C27.5303 325.471 33.6348 328 40 328ZM40 296C41.5823 296 43.129 296.469 44.4446 297.348C45.7602 298.227 46.7855 299.477 47.391 300.939C47.9965 302.4 48.155 304.009 47.8463 305.561C47.5376 307.113 46.7757 308.538 45.6569 309.657C44.538 310.776 43.1126 311.538 41.5607 311.846C40.0089 312.155 38.4003 311.997 36.9385 311.391C35.4767 310.786 34.2273 309.76 33.3482 308.445C32.4692 307.129 32 305.582 32 304C32 301.878 32.8429 299.843 34.3431 298.343C35.8434 296.843 37.8783 296 40 296Z\" fill=\"#114A9F\"><\/path><\/svg>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<a href=\"\/baureinigung\/\" >\n\t\t\t\t\t\t\tBaureinigung\t\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ee883e1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ee883e1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4d02044\" data-id=\"4d02044\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f43ca3 elementor-widget elementor-widget-heading\" data-id=\"3f43ca3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Zus\u00e4tzliche Dienstleistungen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-190108d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"190108d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7077d8b\" data-id=\"7077d8b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9f08b60 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"9f08b60\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">B\u00fcroger\u00e4te Spezialreinigung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Lieferung von Hygieneartikel und Verbrauchsmaterial<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Abfall Entsorgung &amp; Recycling<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Garten Arbeiten<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9117f88\" data-id=\"9117f88\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ba091cb elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"ba091cb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Events &amp; Parties: set up &amp; Reinigung<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Winterdienst<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-check\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">und vieles mehr\u2026<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2b0a5d2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2b0a5d2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-42c0d5a\" data-id=\"42c0d5a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0e7a68c elementor-widget elementor-widget-template\" data-id=\"0e7a68c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"1723\" class=\"elementor elementor-1723\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2e79ea7 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"2e79ea7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2d93343\" data-id=\"2d93343\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f02453a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f02453a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-141ab8c\" data-id=\"141ab8c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-808cf8c elementor-widget elementor-widget-heading\" data-id=\"808cf8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Kostenlose Beratung erhalten<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a9a5687 elementor-widget elementor-widget-text-editor\" data-id=\"a9a5687\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir freuen uns darauf, Ihnen dabei zu helfen, eine saubere, gesunde Umgebung zu schaffen und zu erhalten, die ebenso angenehm wie funktional ist.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8bfe9c elementor-button-align-center elementor-mobile-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"c8bfe9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"Anfrage\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"1723\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"c8bfe9c\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Spezialist f\u00fcr Wohnungsreinigung | Kristall-Klar\" \/>\n\n\t\t\t\t\t\t\t<input type=\"hidden\" name=\"queried_id\" value=\"1866\"\/>\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-md  elementor-field-textual\" placeholder=\"Name\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-50 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-md  elementor-field-textual\" placeholder=\"E-Mail\" required=\"required\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-tel elementor-field-group elementor-column elementor-field-group-message elementor-col-50\">\n\t\t\t\t\t\t\t<input size=\"1\" type=\"tel\" name=\"form_fields[message]\" id=\"form-field-message\" class=\"elementor-field elementor-size-md  elementor-field-textual\" placeholder=\"Telefon\" pattern=\"[0-9()#&amp;+*-=.]+\" title=\"Phone\">\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_c3e605d elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_c3e605d]\" id=\"form-field-field_c3e605d\" class=\"elementor-field elementor-size-md  elementor-field-textual\" placeholder=\"Adresse\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-select elementor-field-group elementor-column elementor-field-group-field_b30470f elementor-col-100\">\n\t\t\t\t\t\t\t<div class=\"elementor-field elementor-select-wrapper remove-before \">\n\t\t\t<div class=\"select-caret-down-wrapper\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-caret-down\"><\/i>\t\t\t<\/div>\n\t\t\t<select name=\"form_fields[field_b30470f]\" id=\"form-field-field_b30470f\" class=\"elementor-field-textual elementor-size-md\">\n\t\t\t\t\t\t\t\t\t<option value=\"\">Bitte w\u00e4hlen...<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Privatreinigung\">Privatreinigung<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"B\u00fcroreinigung\">B\u00fcroreinigung<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Hauswartung\">Hauswartung<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Fenster-Storenreinigung\">Fenster- &amp; Storenreinigung<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Umzugsreinigung\">Umzugsreinigung<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Praxisreinigung\">Praxisreinigung<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Garten-Arbeit\">Garten Arbeit<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Desinfektionsreinigung\">Desinfektionsreinigung<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Fr\u00fchlingsputz\">Fr\u00fchlingsputz<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Grundreinigung\">Grundreinigung<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Winter-Dienst\">Winter Dienst<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Bauendreinigung\">Bauendreinigung<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Eventreinigung\">Eventreinigung<\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"Spezialreinigung \">Spezialreinigung <\/option>\n\t\t\t\t\t\t\t\t\t<option value=\"andere\">andere <\/option>\n\t\t\t\t\t\t\t<\/select>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-field_44d2b18 elementor-col-100\">\n\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-md\" name=\"form_fields[field_44d2b18]\" id=\"form-field-field_44d2b18\" rows=\"4\" placeholder=\"Ihre Anfrage\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-recaptcha_v3 elementor-field-group elementor-column elementor-field-group-field_8499957 elementor-col-100 recaptcha_v3-bottomright\">\n\t\t\t\t\t<div class=\"elementor-field\" id=\"form-field-field_8499957\"><div class=\"elementor-g-recaptcha\" data-sitekey=\"6LfktfQcAAAAAGqxPOau5rQccJALG-P0Dve619Cc\" data-type=\"v3\" data-action=\"Form\" data-badge=\"bottomright\" data-size=\"invisible\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button class=\"elementor-button elementor-size-md\" type=\"submit\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Senden<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>B\u00fcro &amp; Gewerbe Ein sauberes Umfeld ist ein produktives Umfeld Unser 5-Sterne Service hilft mit, Ihrem Team ein Hochleistungsumfeld zu bieten. In welcher Industrie Sie auch arbeiten, dass Arbeitsumfeld beeinflusst Leistung und Produktivit\u00e4t. Unsere erfahrenen Mitarbeiter\/innen sind in der Reinigung spezialisierter B\u00fcroger\u00e4te geschult und arbeiten diskret und respektvoll. Wir arbeiten mit Kunden aus verschiedenen Branchen [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-1715","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Spezialist f\u00fcr B\u00fcroreinigung | Kristall-Klar<\/title>\n<meta name=\"description\" content=\"Vertrauen Sie auf die Qualit\u00e4t von Kristall-Klar f\u00fcr Gewerbe- und B\u00fcroreinigung in Z\u00fcrich, Schwyz, St-Gallen und Zug. Lassen Sie sich kostenlos beraten.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kristall-klar.ch\/en\/offices-commercial\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spezialist f\u00fcr B\u00fcroreinigung | Kristall-Klar\" \/>\n<meta property=\"og:description\" content=\"Vertrauen Sie auf die Qualit\u00e4t von Kristall-Klar f\u00fcr Gewerbe- und B\u00fcroreinigung in Z\u00fcrich, Schwyz, St-Gallen und Zug. Lassen Sie sich kostenlos beraten.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kristall-klar.ch\/en\/offices-commercial\/\" \/>\n<meta property=\"og:site_name\" content=\"Kristall-Klar GmbH | Reinigungsfirma in Z\u00fcrich\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-26T07:38:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kristall-klar.ch\/wp-content\/uploads\/2025\/06\/kristall-klar-015-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1708\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kristall-klar.ch\\\/buro-gewerbe\\\/\",\"url\":\"https:\\\/\\\/kristall-klar.ch\\\/buro-gewerbe\\\/\",\"name\":\"Spezialist f\u00fcr B\u00fcroreinigung | Kristall-Klar\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kristall-klar.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kristall-klar.ch\\\/buro-gewerbe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kristall-klar.ch\\\/buro-gewerbe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kristall-klar.ch\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/kristall-klar-015-scaled.jpg\",\"datePublished\":\"2021-02-23T17:02:23+00:00\",\"dateModified\":\"2025-06-26T07:38:11+00:00\",\"description\":\"Vertrauen Sie auf die Qualit\u00e4t von Kristall-Klar f\u00fcr Gewerbe- und B\u00fcroreinigung in Z\u00fcrich, Schwyz, St-Gallen und Zug. Lassen Sie sich kostenlos beraten.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kristall-klar.ch\\\/buro-gewerbe\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kristall-klar.ch\\\/buro-gewerbe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/kristall-klar.ch\\\/buro-gewerbe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kristall-klar.ch\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/kristall-klar-015-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/kristall-klar.ch\\\/wp-content\\\/uploads\\\/2025\\\/06\\\/kristall-klar-015-scaled.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kristall-klar.ch\\\/buro-gewerbe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kristall-klar.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"B\u00fcro &#038; Gewerbe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kristall-klar.ch\\\/#website\",\"url\":\"https:\\\/\\\/kristall-klar.ch\\\/\",\"name\":\"Kristall-Klar GmbH | Reinigungsfirma in Z\u00fcrich\",\"description\":\"Kristall-Klar ist Ihre vertrauensw\u00fcrdige Z\u00fcrcher Reinigungsfirma f\u00fcr alle Ihre Reinigungsbed\u00fcrfnisse seit 2009. Lassen Sie sich kostenlos beraten.\",\"publisher\":{\"@id\":\"https:\\\/\\\/kristall-klar.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kristall-klar.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kristall-klar.ch\\\/#organization\",\"name\":\"Kristall-Klar GmbH | Reinigungsfirma in Z\u00fcrich\",\"url\":\"https:\\\/\\\/kristall-klar.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/kristall-klar.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kristall-klar.ch\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/cropped-kristalll-klar-logo-mit-frau-rechts.png\",\"contentUrl\":\"https:\\\/\\\/kristall-klar.ch\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/cropped-kristalll-klar-logo-mit-frau-rechts.png\",\"width\":1023,\"height\":245,\"caption\":\"Kristall-Klar GmbH | Reinigungsfirma in Z\u00fcrich\"},\"image\":{\"@id\":\"https:\\\/\\\/kristall-klar.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Spezialist f\u00fcr B\u00fcroreinigung | Kristall-Klar","description":"Trust in the quality of Kristall-Klar for commercial and office cleaning in Zurich, Schwyz, St-Gallen and Zug. Let us advise you free of charge.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kristall-klar.ch\/en\/offices-commercial\/","og_locale":"en_GB","og_type":"article","og_title":"Spezialist f\u00fcr B\u00fcroreinigung | Kristall-Klar","og_description":"Vertrauen Sie auf die Qualit\u00e4t von Kristall-Klar f\u00fcr Gewerbe- und B\u00fcroreinigung in Z\u00fcrich, Schwyz, St-Gallen und Zug. Lassen Sie sich kostenlos beraten.","og_url":"https:\/\/kristall-klar.ch\/en\/offices-commercial\/","og_site_name":"Kristall-Klar GmbH | Reinigungsfirma in Z\u00fcrich","article_modified_time":"2025-06-26T07:38:11+00:00","og_image":[{"width":2560,"height":1708,"url":"https:\/\/kristall-klar.ch\/wp-content\/uploads\/2025\/06\/kristall-klar-015-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kristall-klar.ch\/buro-gewerbe\/","url":"https:\/\/kristall-klar.ch\/buro-gewerbe\/","name":"Spezialist f\u00fcr B\u00fcroreinigung | Kristall-Klar","isPartOf":{"@id":"https:\/\/kristall-klar.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kristall-klar.ch\/buro-gewerbe\/#primaryimage"},"image":{"@id":"https:\/\/kristall-klar.ch\/buro-gewerbe\/#primaryimage"},"thumbnailUrl":"https:\/\/kristall-klar.ch\/wp-content\/uploads\/2025\/06\/kristall-klar-015-scaled.jpg","datePublished":"2021-02-23T17:02:23+00:00","dateModified":"2025-06-26T07:38:11+00:00","description":"Trust in the quality of Kristall-Klar for commercial and office cleaning in Zurich, Schwyz, St-Gallen and Zug. Let us advise you free of charge.","breadcrumb":{"@id":"https:\/\/kristall-klar.ch\/buro-gewerbe\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kristall-klar.ch\/buro-gewerbe\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/kristall-klar.ch\/buro-gewerbe\/#primaryimage","url":"https:\/\/kristall-klar.ch\/wp-content\/uploads\/2025\/06\/kristall-klar-015-scaled.jpg","contentUrl":"https:\/\/kristall-klar.ch\/wp-content\/uploads\/2025\/06\/kristall-klar-015-scaled.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/kristall-klar.ch\/buro-gewerbe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kristall-klar.ch\/"},{"@type":"ListItem","position":2,"name":"B\u00fcro &#038; Gewerbe"}]},{"@type":"WebSite","@id":"https:\/\/kristall-klar.ch\/#website","url":"https:\/\/kristall-klar.ch\/","name":"Kristall-Klar GmbH | Cleaning services in Zurich","description":"Kristall-Klar is your trusted Zurich cleaning company for all your cleaning services since 2009.","publisher":{"@id":"https:\/\/kristall-klar.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kristall-klar.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/kristall-klar.ch\/#organization","name":"Kristall-Klar GmbH | Cleaning services in Zurich","url":"https:\/\/kristall-klar.ch\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/kristall-klar.ch\/#\/schema\/logo\/image\/","url":"https:\/\/kristall-klar.ch\/wp-content\/uploads\/2021\/02\/cropped-kristalll-klar-logo-mit-frau-rechts.png","contentUrl":"https:\/\/kristall-klar.ch\/wp-content\/uploads\/2021\/02\/cropped-kristalll-klar-logo-mit-frau-rechts.png","width":1023,"height":245,"caption":"Kristall-Klar GmbH | Reinigungsfirma in Z\u00fcrich"},"image":{"@id":"https:\/\/kristall-klar.ch\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/kristall-klar.ch\/en\/wp-json\/wp\/v2\/pages\/1715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kristall-klar.ch\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/kristall-klar.ch\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/kristall-klar.ch\/en\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/kristall-klar.ch\/en\/wp-json\/wp\/v2\/comments?post=1715"}],"version-history":[{"count":12,"href":"https:\/\/kristall-klar.ch\/en\/wp-json\/wp\/v2\/pages\/1715\/revisions"}],"predecessor-version":[{"id":11065,"href":"https:\/\/kristall-klar.ch\/en\/wp-json\/wp\/v2\/pages\/1715\/revisions\/11065"}],"wp:attachment":[{"href":"https:\/\/kristall-klar.ch\/en\/wp-json\/wp\/v2\/media?parent=1715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}